{"id":55521,"date":"2025-06-05T15:04:25","date_gmt":"2025-06-05T18:04:25","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/despues-de-el-encargado-guillermo-francella-protagoniza-una-pelicula-en-la-que-encarna-a-16-personajes\/"},"modified":"2025-06-05T15:04:25","modified_gmt":"2025-06-05T18:04:25","slug":"despues-de-el-encargado-guillermo-francella-protagoniza-una-pelicula-en-la-que-encarna-a-16-personajes","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/despues-de-el-encargado-guillermo-francella-protagoniza-una-pelicula-en-la-que-encarna-a-16-personajes\/","title":{"rendered":"Despu\u00e9s de \u201cEl encargado\u201d, Guillermo Francella protagoniza una pel\u00edcula en la que encarna a 16 personajes"},"content":{"rendered":"<div>\n<figure><img fetchpriority=\"high\" width=\"770\" height=\"350\"src=\"https:\/\/i0.wp.com\/www.elsol.com.ar\/wp-content\/uploads\/2021\/07\/1578917429333guillermo20francella.jpg?w=770&amp;ssl=1\" class=\"attachment-rss-image-size size-rss-image-size wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.elsol.com.ar\/wp-content\/uploads\/2021\/07\/1578917429333guillermo20francella.jpg?w=770&amp;ssl=1 770w, https:\/\/i0.wp.com\/www.elsol.com.ar\/wp-content\/uploads\/2021\/07\/1578917429333guillermo20francella.jpg?resize=300%2C136&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.elsol.com.ar\/wp-content\/uploads\/2021\/07\/1578917429333guillermo20francella.jpg?resize=768%2C349&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.elsol.com.ar\/wp-content\/uploads\/2021\/07\/1578917429333guillermo20francella.jpg?resize=400%2C182&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.elsol.com.ar\/wp-content\/uploads\/2021\/07\/1578917429333guillermo20francella.jpg?fit=770%2C350&amp;ssl=1&amp;w=370 370w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\"><\/figure>\n<p><strong>Guillermo Francella<\/strong> se prepara para sorprender una vez m\u00e1s a la audiencia con un proyecto ambicioso y enigm\u00e1tico. Se trata de <strong>\u201cHomo Argentum\u201d<\/strong>, una pel\u00edcula que lo mostrar\u00e1 desdobl\u00e1ndose en 16 personajes distintos, cada uno con su propia historia, conflicto y mensaje.<\/p>\n<p>Este innovador formato presenta cada segmento como una mini-pel\u00edcula aut\u00f3noma, con su propio inicio y final. Sin embargo, la clave de \u201cHomo Argentum\u201d reside en c\u00f3mo todas estas vi\u00f1etas, algunas de apenas un minuto y otras de m\u00e1s de diez, se entrelazan para construir \u201cun espejo deformado y sat\u00edrico de la sociedad argentina actual\u201d. <\/p>\n<p>La propuesta narrativa ha sido comparada con cl\u00e1sicos del cine italiano como \u201cLos Monstruos\u201d, \u201cUn burgu\u00e9s peque\u00f1o, peque\u00f1o\u201d o \u201cLos nuevos monstruos\u201d, por su combinaci\u00f3n de humor \u00e1cido, cr\u00edtica social y personajes que son \u201cexageradamente humanos\u201d.<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title='\"HOMO ARGENTUM\" -  Trailer' width=\"780\" height=\"585\" src=\"https:\/\/www.youtube.com\/embed\/hisfPWzK8O0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<h2 class=\"wp-block-heading\" id=\"h-detalles-del-filme\">Detalles del filme<\/h2>\n<p>Francella asume roles tan diversos como un pol\u00edtico derrotado, un vecino paranoico, un influencer desesperado por atenci\u00f3n o un jubilado enfrentado a la burocracia. Las situaciones presentadas son tan absurdas como reconocibles, buscando provocar \u201cuna herida abierta, una carcajada inc\u00f3moda o una pregunta sin responder\u201d en el espectador.<\/p>\n<p>El gui\u00f3n de esta prometedora cinta fue escrito por <strong>Andr\u00e9s Duprat<\/strong>, habitual colaborador de los reconocidos directores Mariano y Gast\u00f3n Cohn, y cuenta con el aporte creativo de destacadas plumas como Horacio Convertini, Leonardo D\u00b4Esp\u00f3sito, Juan Jos\u00e9 Becerra y Mario Mactas. Esta selecci\u00f3n de autores sugiere un proyecto con una fuerte impronta intelectual y disruptiva, que busca \u201cdesafiar las reglas del relato cl\u00e1sico\u201d.<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El Encargado | Official Trailer | Hulu\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/nVFjlkoolRE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<p><strong>\u201cHomo Argentum\u201d<\/strong> fue rodada durante nueve intensas semanas en Argentina e Italia, manteniendo una estricta reserva sobre los detalles de la producci\u00f3n. Si bien se sabe que las locaciones fueron elegidas por su carga simb\u00f3lica y visual, el contenido espec\u00edfico de cada una de las 16 vi\u00f1etas se mantiene en secreto, alimentando el misterio en torno a la pel\u00edcula.<\/p>\n<p>La producci\u00f3n corre a cargo de Pablo E. Bossi, Cabe Bossi, Pol Bossi y Maxi Lasansky, y se espera que \u201cHomo Argentum\u201d sea uno de los estrenos m\u00e1s provocadores del a\u00f1o. La distribuci\u00f3n estar\u00e1 en manos de Star Distribution, y ya se especula con una posible presentaci\u00f3n especial en alg\u00fan festival antes de <strong>su llegada a las salas de cine el 14 de agosto de 2025.<\/strong><\/p>\n<p>Con informaci\u00f3n de Pronto<\/p>\n<p>The post <a href=\"https:\/\/www.elsol.com.ar\/espectaculos\/despues-de-el-encargado-guillermo-francella-protagoniza-una-pelicula-en-la-que-encarna-a-16-personajes\/\">Despu\u00e9s de \u201cEl encargado\u201d, Guillermo Francella protagoniza una pel\u00edcula en la que encarna a 16 personajes<\/a> appeared first on <a href=\"https:\/\/www.elsol.com.ar\/\">Diario El Sol Mendoza<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Guillermo Francella se prepara para sorprender una vez m\u00e1s a la audiencia con un proyecto ambicioso y enigm\u00e1tico. Se trata de \u201cHomo Argentum\u201d, una pel\u00edcula que lo mostrar\u00e1 desdobl\u00e1ndose en 16 personajes distintos, cada uno con su propia historia, conflicto y mensaje. Este innovador formato presenta cada segmento como una mini-pel\u00edcula aut\u00f3noma, con su propio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-55521","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=55521"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/55532"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=55521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=55521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=55521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}