{"id":45460,"date":"2025-04-01T08:43:21","date_gmt":"2025-04-01T11:43:21","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=45460"},"modified":"2025-04-01T08:43:21","modified_gmt":"2025-04-01T11:43:21","slug":"murio-uno-de-los-humoristas-mas-recordados-de-videomatch","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/murio-uno-de-los-humoristas-mas-recordados-de-videomatch\/","title":{"rendered":"Muri\u00f3 uno de los humoristas m\u00e1s recordados de \u201cVideoMatch\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dolor por la muerte de Toti Ciliberto: se conoci\u00f3 qu\u00e9 le pas\u00f3 al humorista. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/tn.com.ar\/show\/novedades\/2021\/03\/28\/que-es-de-la-vida-de-toti-ciliberto-el-preceptor-y-profesor-de-gimnasia-que-se-gano-el-corazon-de-marcelo-tinelli-en-videomatch\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Toti Ciliberto<\/strong><\/a>&nbsp;muri\u00f3 este martes a los 63 a\u00f1os.&nbsp;<a href=\"https:\/\/tn.com.ar\/show\/famosos\/2023\/09\/06\/larry-de-clay-se-enojo-con-un-companero-porque-hizo-un-comentario-desubicado-sobre-noelia-pompa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Larry de Clay<\/strong><\/a>&nbsp;confirm\u00f3 la noticia en TN y cont\u00f3&nbsp;<strong>c\u00f3mo fueron las \u00faltimas horas<\/strong>&nbsp;del comediante que logr\u00f3 traspasar la pantalla con su inconfundible humor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHab\u00eda tenido un&nbsp;<strong>problema intestinal&nbsp;<\/strong>por tres o cuatro meses\u201d, detall\u00f3 Larry esta ma\u00f1ana al aire de&nbsp;<em>Tempraneros&nbsp;<\/em>cuando Paula Bernini le consult\u00f3 si su colega estaba enfermo. \u201cSe hab\u00eda descompensado, lo internaron de urgencia.&nbsp;<strong>A la madrugada entr\u00f3 en paro<\/strong>\u201d, inform\u00f3 tambi\u00e9n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large wp-duotone-dark-grayscale\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"780\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/04\/descarga-37-800x780.jpg\" alt=\"\" class=\"wp-image-45462\" srcset=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/04\/descarga-37-800x780.jpg 800w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/04\/descarga-37-768x748.jpg 768w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/04\/descarga-37-860x838.jpg 860w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/04\/descarga-37.jpg 900w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Qui\u00e9n era Toti Ciliberto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Salvador \u201cToti\u201d Ciliberto hab\u00eda nacido el 25 de mayo de 1961 dentro de una humilde familia. Su salto a la fama fue junto a&nbsp;<strong>Marcelo Tinelli&nbsp;<\/strong>en&nbsp;<em>Videomatch<\/em>, a mitad de los 90, y era uno de los humoristas que m\u00e1s interactuaba con el conductor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una entrevista con TN Show hab\u00eda contado que su perfil c\u00f3mico lo inici\u00f3 como una reacci\u00f3n al bullying que recib\u00eda cuando era chico. \u201cTen\u00eda un acn\u00e9 muy fuerte y mis pocitos en la cara son la prueba. Me ve\u00eda al espejo y lloraba.&nbsp;<strong>Un d\u00eda me empec\u00e9 a cargar y logr\u00e9 que mis compa\u00f1eros bajaran la agresi\u00f3n.<\/strong>&nbsp;Mi primera relaci\u00f3n con una chica fue porque le ca\u00eda simp\u00e1tico y vio el interior de mi. El secreto es re\u00edrse de uno\u201d, hab\u00eda dicho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trabaj\u00f3 de todo: en corral\u00f3n, una seder\u00eda, una f\u00e1brica de pl\u00e1sticos y&nbsp;<strong>fue profesor de educaci\u00f3n f\u00edsica&nbsp;<\/strong>en una escuela de la ciudad de San Mart\u00edn, en Buenos Aires. All\u00ed lleg\u00f3 a ser preceptor y tambi\u00e9n dio clases en el terciario. Desde ese lugar lleg\u00f3 al humor de la televisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>VideoMatch&nbsp;<\/strong><\/em>no fue lo \u00fanico que hizo en televisi\u00f3n.&nbsp;<strong>Toti condujo&nbsp;<\/strong>el programa&nbsp;<em>Adivina adivinador<\/em>&nbsp;(1997), form\u00f3 parte de&nbsp;<em>Esta noche con Moria Cas\u00e1n<\/em>&nbsp;(2011) y luego, en 2013,&nbsp;<em>La peluquer\u00eda de don Mateo<\/em>, el legendario ciclo de&nbsp;<strong>Gerardo Sofovich<\/strong>. Adem\u00e1s,&nbsp;<strong>incursion\u00f3 en el cine<\/strong>&nbsp;y particip\u00f3 en varias pel\u00edculas:&nbsp;<em>Vivir intentando<\/em>&nbsp;(2003),&nbsp;<em>Brigada explosiva: misi\u00f3n pirata<\/em>&nbsp;(2007),&nbsp;<em>Cuatro de copas<\/em>&nbsp;(2012) y&nbsp;<em>Los bastardos<\/em>&nbsp;(2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En septiembre de 2023 cont\u00f3 que se hab\u00eda convertido al catolicismo hac\u00eda muy poco. \u201c<strong>Dios me est\u00e1 utilizando a trav\u00e9s del humor para acercar a mucha gente al cristianismo<\/strong>\u201d, hab\u00eda dicho durante un show en Rosario junto al predicador de su iglesia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dolor por la muerte de Toti Ciliberto: se conoci\u00f3 qu\u00e9 le pas\u00f3 al humorista. Toti Ciliberto&nbsp;muri\u00f3 este martes a los 63 a\u00f1os.&nbsp;Larry de Clay&nbsp;confirm\u00f3 la noticia en TN y cont\u00f3&nbsp;c\u00f3mo fueron las \u00faltimas horas&nbsp;del comediante que logr\u00f3 traspasar la pantalla con su inconfundible humor. \u201cHab\u00eda tenido un&nbsp;problema intestinal&nbsp;por tres o cuatro meses\u201d, detall\u00f3 Larry esta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-45460","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/45460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=45460"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/45460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/45461"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=45460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=45460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=45460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}