{"id":225684,"date":"2026-05-13T10:13:00","date_gmt":"2026-05-13T13:13:00","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=225684"},"modified":"2026-05-13T12:22:42","modified_gmt":"2026-05-13T15:22:42","slug":"saenz-pena-se-realizo-el-primer-torneo-de-ajedrez-escolar-del-2026","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/saenz-pena-se-realizo-el-primer-torneo-de-ajedrez-escolar-del-2026\/","title":{"rendered":"S\u00e1enz Pe\u00f1a: Se realiz\u00f3 el primer torneo de ajedrez escolar del 2026"},"content":{"rendered":"\n<p>En la ma\u00f1ana del Martes &nbsp;se realiz\u00f3 el 1\u00b0 Torneo de Ajedrez escolar en la Escuela 453 del B\u00b0 Puerta del Sol. Participaron un total de 67 alumnos de 7\u00b0 grado a 5 rondas por encuentro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.47.jpeg?ssl=1\" alt=\"\" class=\"wp-image-225687\"\/><\/figure>\n\n\n\n<p>El proyecto comenz\u00f3 en marzo con clases en este establecimiento educativo, tambi\u00e9n en el 221, 990 y 327, turnos ma\u00f1ana y tarde y en la escuela rural N\u00b0 155. El profesor Mart\u00edn Busto, a cargo de la escuela municipal de Ajedrez destac\u00f3 que &#8220;estuvo muy parejo en los primeros puestos&#8221;.<br>Acompa\u00f1aron la premiaci\u00f3n el Intendente Bruno, Cipolini, Pedro Egea y la Concejal Soledad Perez.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i3.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-20.49.46-1.jpeg?ssl=1\" alt=\"\" class=\"wp-image-225685\"\/><\/figure>\n\n\n\n<p><br><strong>Los premiados:<br><\/strong>1- Rodriguez, Ian<br>2- Quinteros, Gian<br>3- Altamirano, Facundo.<br>4- Soles, Yamila<br>5- Longui, Clara<br>6- D\u00edaz, Santino,<br>7- Altamirano, Antony<\/p>\n\n\n\n<p><strong>Mejor Femenino:<br><\/strong>&#8211; Sandero, Renata<br>&#8211; Melavidovich, Renata<br>&#8211; Sandero, Renata<\/p>\n\n\n\n<p><strong>Destacados:<br><\/strong>&#8211; Gianola, Gabriela<br>&#8211; Herrera, Maximo<br>&#8211; G\u00f3mez, Gabriel<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana del Martes &nbsp;se realiz\u00f3 el 1\u00b0 Torneo de Ajedrez escolar en la Escuela 453 del B\u00b0 Puerta del Sol. Participaron un total de 67 alumnos de 7\u00b0 grado a 5 rondas por encuentro. El proyecto comenz\u00f3 en marzo con clases en este establecimiento educativo, tambi\u00e9n en el 221, 990 y 327, turnos [&hellip;]<\/p>\n","protected":false},"author":10001,"featured_media":225686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[628],"class_list":{"0":"post-225684","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chaco","8":"tag-saenzpena"},"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/225684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/10001"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=225684"}],"version-history":[{"count":1,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/225684\/revisions"}],"predecessor-version":[{"id":225689,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/225684\/revisions\/225689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/225686"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=225684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=225684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=225684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}