{"id":225325,"date":"2026-05-12T11:04:10","date_gmt":"2026-05-12T14:04:10","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/jimmy-kimmel-john-oliver-seth-meyers-y-jimmy-fallon-hablaron-sobre-la-obsesion-de-trump-con-sus-ciclos_a6a03229e4d461d30016b939b\/"},"modified":"2026-05-12T11:04:10","modified_gmt":"2026-05-12T14:04:10","slug":"jimmy-kimmel-john-oliver-seth-meyers-y-jimmy-fallon-hablaron-sobre-la-obsesion-de-trump-con-sus-ciclos_a6a03229e4d461d30016b939b","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/jimmy-kimmel-john-oliver-seth-meyers-y-jimmy-fallon-hablaron-sobre-la-obsesion-de-trump-con-sus-ciclos_a6a03229e4d461d30016b939b\/","title":{"rendered":"Jimmy Kimmel, John Oliver, Seth Meyers y Jimmy Fallon hablaron sobre la obsesi\u00f3n de Trump con sus ciclos"},"content":{"rendered":"<p><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1\" \/><\/p>\n<div itemprop=\"articleBody\">\n<p><a href=\"\/\"><strong>Buenos Aires, 12 mayo (NA)<\/strong> \u2013<\/a> \u00a0Los referentes del late night show estadounidense, <strong>Jimmy Kimmel, John Oliver, Seth Meyers y Jimmy Fallon<\/strong> se unieron a <strong>Stephen Colbert<\/strong> en el ic\u00f3nico sill\u00f3n de <i>The Late Show<\/i> y hablaron de la &#8220;obsesi\u00f3n&#8221; del presidente Donald Trump con sus programas nocturnos.\u00a0<\/p>\n<p>Seg\u00fan supo la <strong>Agencia Noticias Argentinas<\/strong>, el encuentro entre conductores funcion\u00f3 como una despedida para Colbert, cuyo ciclo en <i>The Late Show<\/i> llegar\u00e1 a su fin de manera definitiva el pr\u00f3ximo <strong>21 de mayo<\/strong>. Su programa fue cancelado por la se\u00f1al CBS por motivos financieros.\u00a0<\/p>\n<p>Durante la charla, Colbert les pidi\u00f3 a sus colegas que &#8220;defiendan a los programas nocturnos&#8221;, frente al bajo consumo de televisi\u00f3n que atraviesa Estados Unidos y el mundo durante los \u00faltimos a\u00f1os.\u00a0<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-01\"\/><\/p>\n<p><strong>Jimmy Kimmel <\/strong>fue el primero en tomar la palabra, mencionando su sorpresa al notar la gran popularidad que tienen los late night shows. En esta oportunidad se us\u00f3 a s\u00ed mismo de ejemplo y record\u00f3 la gran repercusi\u00f3n que tuvo &#8220;Jimmy Kimmel Live!&#8221; cuando fue suspendido unos d\u00edas del aire, tras su cruce con el presidente estadounidense <strong>Donald Trump<\/strong>.\u00a0<\/p>\n<p><strong>\u201cTenemos muchos programas. 30.000 personas ven cada uno, y eso suma\u201d<\/strong>, dijo Kimmel. <strong>\u201cAhora la gente nos ve en YouTube. Tienen muchas opciones diferentes y siguen viniendo a nosotros. Les dir\u00e9 algo: cuando me sacaron del aire por unos d\u00edas, la gente cancel\u00f3 Disney+. \u00bfPor qu\u00e9 no cancelan Paramount+? \u00bfPorque nunca lo tuvieron?\u201d<\/strong>, se cuestion\u00f3 con su humor \u00e1cido.\u00a0<\/p>\n<p>Cuando el show de Kimmel sali\u00f3 del aire, m\u00faltiples actores, figuras y colegas alzaron su voz frente a la injusticia y denunciaron un quiebre en la libertad de expresi\u00f3n. Finalmente, el ciclo volvi\u00f3 a rotar con normalidad.\u00a0<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-02\"\/><\/p>\n<p>Habiendo tocado el tema, Colbert le pregunt\u00f3 al resto de los conductores con pasado en la comedia si se hab\u00edan imaginado que su trabajo &#8220;provocar\u00eda fuertes reacciones en el Presidente de los Estados Unidos&#8221;.<\/p>\n<p>Kimmel volvi\u00f3 a tomar la palabra y lanz\u00f3 &#8220;\u00bfSaben qu\u00e9 es a\u00fan m\u00e1s extra\u00f1o? Hacer un trabajo sobre el que su esposa tiene opiniones tan firmes&#8221;. Meyers intervino con iron\u00eda sobre el reciente cruce entre Melania Trump y Jimmy: &#8220;La mayor\u00eda de nosotros hemos evitado esa parte&#8221;, sum\u00f3.\u00a0<\/p>\n<p>John Oliver, conductor de Last Week Tonight, record\u00f3 el instante en el que se enteraron del nuevo enfrentamiento entre Kimmel y la familia presidencial: \u201cEs incre\u00edble recibir, en un chat grupal, un mensaje de Jimmy que dice: &#8216;\u00a1Ay, Dios m\u00edo!&#8217;. Y luego una foto de Melania enojada con \u00e9l\u201d.<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-03\"\/><\/p>\n<p style=\"--ipspy: __IP__;color: __IP__;text-decoration: __IP__;\" alt=\"__IP__\" data-ipspy=\"__IP__\" title=\"__IP__\">Con un toque de sarcasmo, Seth Meyers se\u00f1al\u00f3 que los ataques de Trump en redes son un halago para \u00e9l, porque significa que lo est\u00e1 viendo en directo y, de esa manera indirecta, apoya el programa.<span style=\"opacity: 0;\" data-nosnippet=\"\">__IP__<\/span><\/p>\n<p>&#8220;Lo que me gusta es que publica cu\u00e1ndo se emite el programa, y \u200b\u200bquiero decir que aprecio que est\u00e9 viendo la televisi\u00f3n tradicional\u201d, dijo Meyers con humor. \u201cSi tuviera que defender la programaci\u00f3n nocturna, dir\u00eda que los l\u00edderes del mundo libre la ven cuando se emite\u201d, agreg\u00f3.<\/p>\n<p><a href=\"\/-agenciana_t6916e70a4551e78eb9423f59\">#AgenciaNA<\/a>\u00a0<\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i0.wp.com\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/05\/1778594650_109_Jimmy-Kimmel-John-Oliver-Seth-Meyers-y-Jimmy-Fallon-hablaron.jpeg?ssl=1\"><\/p>\n<p>Noticias Argentinas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 12 mayo (NA) \u2013 \u00a0Los referentes del late night show estadounidense, Jimmy Kimmel, John Oliver, Seth Meyers y Jimmy Fallon se unieron a Stephen Colbert en el ic\u00f3nico sill\u00f3n de The Late Show y hablaron de la &#8220;obsesi\u00f3n&#8221; del presidente Donald Trump con sus programas nocturnos.\u00a0 Seg\u00fan supo la Agencia Noticias Argentinas, el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":225336,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":{"0":"post-225325","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-farandula"},"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/225325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=225325"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/225325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/225336"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=225325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=225325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=225325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}