{"id":219112,"date":"2026-04-22T09:43:00","date_gmt":"2026-04-22T12:43:00","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=219112"},"modified":"2026-04-22T10:27:02","modified_gmt":"2026-04-22T13:27:02","slug":"emotivo-homenaje-al-papa-francisco-en-la-legislatura-su-legado-es-un-norte-para-nuestra-sociedad","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/emotivo-homenaje-al-papa-francisco-en-la-legislatura-su-legado-es-un-norte-para-nuestra-sociedad\/","title":{"rendered":"Emotivo homenaje al Papa Francisco en la Legislatura: \u201cSu legado es un norte para nuestra sociedad\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En un marco de profunda emotividad, el Poder Legislativo del Chaco realiz\u00f3 un homenaje p\u00f3stumo a Su Santidad, el Papa Francisco, al cumplirse el primer aniversario de su paso a la inmortalidad. El acto se realiz\u00f3 en el Recinto de Sesiones \u201cEsc. Deolindo Felipe Bittel\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ceremonia fue encabezada por la presidente de la Legislatura, Carmen Delgado, junto a los autores de la iniciativa: la vicepresidente primera, Susana Maggio, y el diputado Sebasti\u00e1n Ben\u00edtez Molas. El evento cont\u00f3 con una presencia de especial relevancia: Juan Fern\u00e1ndez Xifra, sobrino del Santo Padre, quien fue invitado a integrar la mesa principal en reconocimiento a su v\u00ednculo familiar. Acompa\u00f1aron la jornada los legisladores Mar\u00eda Elena Rodr\u00edguez, Edgardo Reguera, Carina Botteri, Maida With y Anal\u00eda Flores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su discurso, la titular de la Legislatura, Carmen Delgado, subray\u00f3 la vigencia del mensaje papal: \u201cHoy homenajeamos a una persona que nos ense\u00f1\u00f3 valores que debemos aplicar en nuestras acciones, como mirar al m\u00e1s d\u00e9bil\u201d. Asimismo, destac\u00f3 la madurez pol\u00edtica de los autores del homenaje: \u201cFelicito a los diputados Maggio y Molas por esta iniciativa conjunta, a pesar de pertenecer a bloques distintos. Francisco nos ense\u00f1\u00f3 valores de honestidad, coherencia y compasi\u00f3n que son un norte para nuestros j\u00f3venes\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"http:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4.jpeg\" alt=\"\" class=\"wp-image-219114\" srcset=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4.jpeg 1600w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4-768x512.jpeg 768w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4-1536x1023.jpeg 1536w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4-330x220.jpeg 330w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4-420x280.jpeg 420w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4-615x410.jpeg 615w, https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/04\/Homenaje-al-Papa-Francisco-4-860x573.jpeg 860w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la diputada Susana Maggio record\u00f3 la fecha como una jornada de reflexi\u00f3n: \u201cHoy se cumple un a\u00f1o de la Pascua del Papa Francisco. Nos reunimos para honrar su humildad y su obediencia a Dios\u201d. En sinton\u00eda, el legislador Ben\u00edtez Molas defini\u00f3 al Pont\u00edfice como un visionario: \u201cFue un misionero que sac\u00f3 a la Iglesia de la comodidad para acercarla a los m\u00e1rgenes; nos alert\u00f3 sobre la globalizaci\u00f3n de la indiferencia y la cultura del descarte\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El recinto luci\u00f3 una escultura del Papa Francisco, realizada por el artista Santiago Guarneri, la cual ser\u00e1 emplazada pr\u00f3ximamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, participaron los diputados con mandato cumplido Mariela Quir\u00f3s y Olga B\u00e9rtoli. Tambi\u00e9n formaron parte del acto integrantes de la Mesa Interreligiosa, representantes de la comunidad religiosa local y delegaciones escolares, uniendo a distintos sectores de la sociedad en el recuerdo del l\u00edder religioso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un marco de profunda emotividad, el Poder Legislativo del Chaco realiz\u00f3 un homenaje p\u00f3stumo a Su Santidad, el Papa Francisco, al cumplirse el primer aniversario de su paso a la inmortalidad. El acto se realiz\u00f3 en el Recinto de Sesiones \u201cEsc. Deolindo Felipe Bittel\u201d. La ceremonia fue encabezada por la presidente de la Legislatura, [&hellip;]<\/p>\n","protected":false},"author":10001,"featured_media":219113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[202],"class_list":["post-219112","post","type-post","status-publish","format-standard","has-post-thumbnail","category-chaco","tag-legislatura"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/219112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/10001"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=219112"}],"version-history":[{"count":1,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/219112\/revisions"}],"predecessor-version":[{"id":219116,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/219112\/revisions\/219116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/219113"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=219112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=219112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=219112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}