{"id":207931,"date":"2026-03-05T17:04:55","date_gmt":"2026-03-05T20:04:55","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/britney-spears-fue-liberada-tras-estar-arrestada-por-conducir-alcoholizada_a69a9a650c331fb25186b3896\/"},"modified":"2026-03-05T17:04:55","modified_gmt":"2026-03-05T20:04:55","slug":"britney-spears-fue-liberada-tras-estar-arrestada-por-conducir-alcoholizada_a69a9a650c331fb25186b3896","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/britney-spears-fue-liberada-tras-estar-arrestada-por-conducir-alcoholizada_a69a9a650c331fb25186b3896\/","title":{"rendered":"Britney Spears fue liberada tras ser arrestada por conducir ebria"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/03\/Britney-Spears-fue-liberada-tras-ser-arrestada-por-conducir-ebria.jpeg\" \/><\/p>\n<div itemprop=\"articleBody\">\n<p><a href=\"https:\/\/noticiasargentinas.com\/?srsltid=AfmBOope390rrKB5iyBpgJytfT38SpaetUEf_4QXR8dLRukB9SVht-Us\"><strong>Buenos Aires, 5 marzo (NA) \u2013<\/strong><\/a> La cantante <span><strong>Britney Spears<\/strong><\/span> fue detenida en California tras ser interceptada por la polic\u00eda bajo sospecha de conducir bajo los efectos del alcohol.\u00a0<\/p>\n<p>El episodio ocurri\u00f3 el mi\u00e9rcoles por la noche en <span><strong>Condado de Ventura<\/strong><\/span>, seg\u00fan supo la <a href=\"https:\/\/noticiasargentinas.com\/?srsltid=AfmBOope390rrKB5iyBpgJytfT38SpaetUEf_4QXR8dLRukB9SVht-Us\"><strong>Agencia Noticias Argentinas<\/strong><\/a> a trav\u00e9s de autoridades locales.<\/p>\n<p>De acuerdo con la informaci\u00f3n difundida por medios estadounidenses, la artista de 44 a\u00f1os fue detenida alrededor de las <strong>21:30<\/strong> luego de que agentes de la <span><strong>California Highway Patrol<\/strong><\/span> (Patrulla de Carreteras de California) frenaran su veh\u00edculo durante un control.<\/p>\n<p>Tras el procedimiento, Spears fue arrestada y trasladada bajo custodia y, seg\u00fan report\u00f3 el portal TMZ, la cantante fue esposada en el lugar y permaneci\u00f3 detenida durante varias horas.<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-01\"\/><\/p>\n<p style=\"--ipspy: __IP__;color: __IP__;text-decoration: __IP__;\" alt=\"__IP__\" data-ipspy=\"__IP__\" title=\"__IP__\">Los registros oficiales indican que la int\u00e9rprete recuper\u00f3 la libertad cerca de las <strong>6 de la ma\u00f1ana del jueves<\/strong>, bajo la modalidad conocida como <strong>\u201ccitaci\u00f3n y liberaci\u00f3n\u201d<\/strong>, un procedimiento mediante el cual el acusado queda en libertad pero debe presentarse posteriormente ante la Justicia.<span style=\"opacity: 0;\" data-nosnippet=\"\">__IP__<\/span><\/p>\n<p>En ese marco, Spears deber\u00e1 comparecer ante un tribunal por este incidente el pr\u00f3ximo <strong>4 de mayo<\/strong>.<\/p>\n<p>Por el momento, las autoridades no brindaron m\u00e1s detalles sobre el episodio ni sobre las circunstancias exactas que derivaron en la detenci\u00f3n. Tampoco hubo declaraciones p\u00fablicas por parte de la artista ni de sus representantes. <a href=\"\/-agenciana_t6916e70a4551e78eb9423f59\">#AgenciaNA<\/a>\u00a0<\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"http:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/03\/1772741095_258_Britney-Spears-fue-liberada-tras-ser-arrestada-por-conducir-ebria.jpeg\"><\/p>\n<p>Noticias Argentinas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 5 marzo (NA) \u2013 La cantante Britney Spears fue detenida en California tras ser interceptada por la polic\u00eda bajo sospecha de conducir bajo los efectos del alcohol.\u00a0 El episodio ocurri\u00f3 el mi\u00e9rcoles por la noche en Condado de Ventura, seg\u00fan supo la Agencia Noticias Argentinas a trav\u00e9s de autoridades locales. De acuerdo con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":207942,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-207931","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/207931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=207931"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/207931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/207942"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=207931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=207931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=207931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}