{"id":206571,"date":"2026-02-25T14:03:03","date_gmt":"2026-02-25T17:03:03","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/fuerte-critica-de-cristian-u-a-gran-hermano-me-parece-un-horror-el-casting-que-hicieron-_a699f1d5dc331fb25182082a9\/"},"modified":"2026-02-25T14:03:03","modified_gmt":"2026-02-25T17:03:03","slug":"fuerte-critica-de-cristian-u-a-gran-hermano-me-parece-un-horror-el-casting-que-hicieron-_a699f1d5dc331fb25182082a9","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/fuerte-critica-de-cristian-u-a-gran-hermano-me-parece-un-horror-el-casting-que-hicieron-_a699f1d5dc331fb25182082a9\/","title":{"rendered":"Fuerte cr\u00edtica de Cristian U a Gran Hermano: \u201cMe parece un horror el casting que hicieron\u201d"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/02\/Fuerte-critica-de-Cristian-U-a-Gran-Hermano-Me-parece.jpeg\" \/><\/p>\n<div itemprop=\"articleBody\">\n<p><a rel=\"noopener nofollow\" href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\"><strong>Buenos Aires, 25 febrero (NA)<\/strong><\/a> \u2013 El estreno de <strong>Gran Hermano: Generaci\u00f3n Dorada<\/strong> en Telefe logr\u00f3 captar la atenci\u00f3n del p\u00fablico y buenos n\u00fameros de rating, pero no estuvo exento de cuestionamientos. Uno de los m\u00e1s duros fue <strong>Cristian U<\/strong>, ganador de la edici\u00f3n 2011, quien critic\u00f3 con fuerza el perfil de los participantes y el armado del casting.<\/p>\n<p>Seg\u00fan pudo comprobar la Agencia Noticias Argentinas, en di\u00e1logo con Gustavo M\u00e9ndez para La Posta del Espect\u00e1culo, el ex GH utiliz\u00f3 una met\u00e1fora filosa: <i><strong>\u201cEs como tener una Ferrari con la P de principiante\u201d<\/strong><\/i>.<\/p>\n<p><i><strong>\u201cMe parece un horror que hagan este tipo de casting y pongan a gente que no tiene sentido. Dec\u00eds: \u2018loco, te van a chocar la Ferrari\u2019. Est\u00e1 buen\u00edsima, no la rompas\u201d,<\/strong><\/i> agreg\u00f3, seg\u00fan supo la <a rel=\"noopener nofollow\" href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\">Agencia Noticias Argentinas<\/a>.<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-01\"\/><\/p>\n<p>Cristian U fue especialmente tajante al referirse al ingreso de <strong>Andrea del Boca<\/strong>. \u201c<i><strong>Es una locura invertir un mont\u00f3n de d\u00f3lares en un personaje que no representa nada de lo que es el reality\u201d<\/strong><\/i>, sostuvo. <i>\u201cSacala a Andrea del Boca y ponela a Furia. Mir\u00e1 lo que te voy a decir, estoy re loco. Sacala a Andrea del Boca y ponela a Catalina Gorostidi&#8221;<\/i>, propuso el ex GH.<\/p>\n<p style=\"--ipspy: __IP__;color: __IP__;text-decoration: __IP__;\" alt=\"__IP__\" data-ipspy=\"__IP__\" title=\"__IP__\"><i><strong>\u201cNo hay representaci\u00f3n de la gente com\u00fan, est\u00e1 todo totalmente digitado. En mi Gran Hermano nadie era conocido. \u00c9ramos pibes con hambre, con ilusi\u00f3n, que no sab\u00edamos lo que era una c\u00e1mara\u201d<\/strong><\/i>, detall\u00f3 Cristian.<span style=\"opacity: 0;\" data-nosnippet=\"\">__IP__<\/span><\/p>\n<p>El ganador de 2011 tambi\u00e9n apunt\u00f3 contra el conductor <strong>Santiago del Moro <\/strong>y lo compar\u00f3 con <strong>Jorge Rial<\/strong>, quien estaba al frente del ciclo durante su participaci\u00f3n. <i>\u201cCada chanchito tiene su corral. La producci\u00f3n tiene que hacer el casting, el conductor no deber\u00eda elegir ni pedir favores\u201d<\/i>, sentenci\u00f3.<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-02\"\/><\/p>\n<p>Y cerr\u00f3 con una diferencia clave: \u201cDel Moro no me mata porque no provoca el conflicto que generaba Rial. Con tres palabras nos hac\u00eda desconfiar a todos\u201d. <a href=\"\/-agenciana_t6916e70a4551e78eb9423f59\">#AgenciaNA<\/a>\u00a0<\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"http:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/02\/1772038979_375_Fuerte-critica-de-Cristian-U-a-Gran-Hermano-Me-parece.jpeg\"><\/p>\n<p>Noticias Argentinas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 25 febrero (NA) \u2013 El estreno de Gran Hermano: Generaci\u00f3n Dorada en Telefe logr\u00f3 captar la atenci\u00f3n del p\u00fablico y buenos n\u00fameros de rating, pero no estuvo exento de cuestionamientos. Uno de los m\u00e1s duros fue Cristian U, ganador de la edici\u00f3n 2011, quien critic\u00f3 con fuerza el perfil de los participantes y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":206582,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-206571","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/206571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=206571"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/206571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/206582"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=206571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=206571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=206571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}