{"id":195836,"date":"2026-01-22T08:03:52","date_gmt":"2026-01-22T11:03:52","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/mitomana-el-descargo-de-icardi-contra-wanda-tras-los-rumores-de-reconciliacion_a6971f6eecbf033dd99b9732e\/"},"modified":"2026-01-22T08:03:52","modified_gmt":"2026-01-22T11:03:52","slug":"mitomana-el-descargo-de-icardi-contra-wanda-tras-los-rumores-de-reconciliacion_a6971f6eecbf033dd99b9732e","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/mitomana-el-descargo-de-icardi-contra-wanda-tras-los-rumores-de-reconciliacion_a6971f6eecbf033dd99b9732e\/","title":{"rendered":"\u201cMit\u00f3mana\u201d: el descargo de Icardi contra Wanda tras los rumores de reconciliaci\u00f3n"},"content":{"rendered":"<p><\/p>\n<div itemprop=\"articleBody\">\n<p><a href=\"\/\"><strong>Buenos Aires, 22 enero (NA)<\/strong> <\/a>\u2013 La guerra medi\u00e1tica entre <strong>Mauro Icardi <\/strong>y <strong>Wanda Nara<\/strong> parece no tener fin y, tras un breve per\u00edodo de calma, las recientes declaraciones de la empresaria enfurecieron al futbolista, quien reaccion\u00f3 con un dur\u00edsimo comunicado en el que calific\u00f3 a su ex pareja de <strong>\u201cmit\u00f3mana\u201d<\/strong>.<\/p>\n<p>La conductora de MasterChef Celebrity hab\u00eda asegurado en un m\u00f3vil de <i>Intrusos <\/i>que <a href=\"http:\/\/noticiasargentinas.com\/espectaculos\/wanda-nara-y-sus--charlas--con-mauro-icardi---le-digo--solta--ya-fue---_a697132d0cbf033dd99ad00d1\">\u201cmantiene mucho di\u00e1logo\u201d con el padre de sus hijas <\/a>y que la relaci\u00f3n hab\u00eda mejorado, subrayando que para ella, \u201c<i><strong>\u00e9l siempre ser\u00e1 familia<\/strong><\/i>\u201d, comunic\u00f3 la <a rel=\"noopener nofollow\" href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\"><strong>Agencia Noticias Argentinas<\/strong><\/a><strong>.<\/strong><\/p>\n<p>Sin embargo, a Icardi le molest\u00f3 que Nara intentara instalar una versi\u00f3n de reconciliaci\u00f3n y utiliz\u00f3 sus redes sociales para publicar un fuerte y extenso descargo.<\/p>\n<p>&#8220;<strong>Voy a ser bien claro: las declaraciones de esta mujer son falsas<\/strong>&#8220;, arranc\u00f3 el deportista, visiblemente molesto por las versiones de di\u00e1logo que circularon. \u201c<strong>Resulta llamativo que se le siga creyendo a una persona mit\u00f3mana<\/strong>, no por lo que yo diga, sino por lo que demuestran sus propios actos\u201d, sum\u00f3.<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-01\"\/><\/p>\n<p style=\"--ipspy: __IP__;color: __IP__;text-decoration: __IP__;\" alt=\"__IP__\" data-ipspy=\"__IP__\" title=\"__IP__\">Icardi enumer\u00f3 al menos 12 razones -entre ellas, las denuncias por violencia de g\u00e9nero, el impedimento de visitas a sus hijas, las denuncias de violencia infantil a los hijos de<strong> Maxi L\u00f3pez<\/strong> y el hostigamiento a<strong> Eugenia \u201cChina\u201d Su\u00e1rez<\/strong>&#8211; por las cuales <strong>confirma que &#8220;NUNCA retomar\u00eda ning\u00fan tipo de di\u00e1logo, ni v\u00ednculo<\/strong>\u201d con una persona como ella.\u00a0<span style=\"opacity: 0;\" data-nosnippet=\"\">__IP__<\/span><\/p>\n<p>Uno de los puntos m\u00e1s impactantes del descargo fue la acusaci\u00f3n econ\u00f3mica que mencion\u00f3 en varias ocasiones: <strong>&#8220;Me rob\u00f3 siete millones de euros, hecho que ya es de conocimiento p\u00fablico&#8221;<\/strong>, denunci\u00f3 y tambi\u00e9n hizo una menci\u00f3n al ex abogado de Wanda, Nicol\u00e1s Payarola, a cargo de las causas familiares, a quien defini\u00f3 como un &#8220;estafador y corrupto&#8221;.<\/p>\n<p>Cerrando cualquier puerta a la reconciliaci\u00f3n, sentenci\u00f3: \u201c<strong>Que quede absolutamente claro: esta persona en mi vida es solamente la madre de mis hijas. Nunca, jam\u00e1s, ser\u00e1 familia\u201d<\/strong>. <a href=\"\/-agenciana_t6916e70a4551e78eb9423f59\">#AgenciaNA<\/a>\u00a0<\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-02\"\/><\/p>\n<figure class=\"multimedia\" data-tadevel-template=\"web\/multimedia\" data-type=\"photo\">\n<div class=\"content\">\n<div class=\"sizer\" data-sizer=\"aspect-ratio\" data-tadevel-template=\"web\/aspect-ratio\" style=\"--aspect-ratio:179.37219730941703%;\"><picture data-tadevel-template=\"web\/picture\"><source   type=\"image\/webp\"><source   type=\"image\/jpeg\"><img alt=\"\u201cMit\u00f3mana\u201d: el descargo de Icardi contra Wanda tras los rumores de reconciliaci\u00f3n\" loading=\"lazy\" style=\"object-position:center;\"\/><x-picture-helper\/><\/source><\/source><\/picture><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/01\/Mitomana-el-descargo-de-Icardi-contra-Wanda-tras-los-rumores.jpeg\"><\/p>\n<p>Noticias Argentinas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 22 enero (NA) \u2013 La guerra medi\u00e1tica entre Mauro Icardi y Wanda Nara parece no tener fin y, tras un breve per\u00edodo de calma, las recientes declaraciones de la empresaria enfurecieron al futbolista, quien reaccion\u00f3 con un dur\u00edsimo comunicado en el que calific\u00f3 a su ex pareja de \u201cmit\u00f3mana\u201d. La conductora de MasterChef [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":195847,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-195836","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/195836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=195836"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/195836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/195847"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=195836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=195836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=195836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}