{"id":189945,"date":"2026-01-12T11:07:49","date_gmt":"2026-01-12T14:07:49","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/quien-es-maia-reficco-la-actriz-que-estaria-en-pareja-con-franco-colapinto_a6964d9d3cbf033dd999a14dc\/"},"modified":"2026-01-12T11:07:49","modified_gmt":"2026-01-12T14:07:49","slug":"quien-es-maia-reficco-la-actriz-que-estaria-en-pareja-con-franco-colapinto_a6964d9d3cbf033dd999a14dc","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/quien-es-maia-reficco-la-actriz-que-estaria-en-pareja-con-franco-colapinto_a6964d9d3cbf033dd999a14dc\/","title":{"rendered":"Qui\u00e9n es Maia Reficco, la actriz que estar\u00eda en pareja con Franco Colapinto"},"content":{"rendered":"<p><\/p>\n<div itemprop=\"articleBody\">\n<p><a href=\"\/\"><strong>Buenos Aires, 12 enero (NA)<\/strong><\/a> \u2013 La actriz <strong>Maia Reficco <\/strong>se convirti\u00f3 en tapa de portales al ser se\u00f1alada como la nueva pareja del piloto de F\u00f3rmula 1, <strong>Franco Colapinto<\/strong>, luego de que \u00e9l compartiera una foto de ella usando su casco.<\/p>\n<p>Los rumores se alimentaron cuando vieron que el corredor hab\u00eda parafraseado un posteo que Reficco hab\u00eda publicado d\u00edas atr\u00e1s, pero, seg\u00fan supo la <a rel=\"noopener nofollow\" href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\"><strong>Agencia Noticias Argentinas<\/strong><\/a><strong>,<\/strong> ninguno de los protagonistas confirm\u00f3 el romance hasta el momento.\u00a0<\/p>\n<h3>Qui\u00e9n es Maia Reficco<\/h3>\n<p>Reficco es una actriz de 25 a\u00f1os nacida en Boston, Estados Unidos, pero criada en Buenos Aires, Argentina, desde sus 7 a\u00f1os. Tiene una doble nacionalidad, pero se reconoce argentina.\u00a0<\/p>\n<figure class=\"multimedia\" data-tadevel-template=\"web\/multimedia\" data-type=\"photo\">\n<div class=\"content\">\n<div class=\"sizer\" data-sizer=\"aspect-ratio\" data-tadevel-template=\"web\/aspect-ratio\" style=\"--aspect-ratio:124.35185185185186%;\"><picture data-tadevel-template=\"web\/picture\"><source   type=\"image\/webp\"><source   type=\"image\/jpeg\"><img alt=\"Qui\u00e9n es Maia Reficco, la actriz que estar\u00eda en pareja con Franco Colapinto\" loading=\"lazy\" style=\"object-position:center;\"\/><x-picture-helper\/><\/source><\/source><\/picture><\/div>\n<\/div>\n<\/figure>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-01\"\/><\/p>\n<p>Su madre es la vocalista de famosos, como Tini y Abel Pintos,<strong> Katie Viqueira<\/strong>, y su hermano es <strong>Joaqu\u00edn Reficco<\/strong>, actor de la serie de Cris Morena, <i><strong>Margarita<\/strong><\/i>. Desde peque\u00f1a tuvo un gran inter\u00e9s por la m\u00fasica, llegando a tocar 4 instrumentos durante su juventud.<\/p>\n<p style=\"--ipspy: __IP__;color: __IP__;text-decoration: __IP__;\" alt=\"__IP__\" data-ipspy=\"__IP__\" title=\"__IP__\">Su debut actoral fue en 2017 en la serie de Nickelodeon<strong> Kally&#8217;s Mashup<\/strong>, como Kally Ponce, logrando una fama en todo Latinoam\u00e9rica. En 2019 dio su gran salto hacia Estados Unidos y se convirti\u00f3 en la primera actriz en interpretar a Evita en el New York City Center a la corta edad de 18 a\u00f1os.\u00a0<span style=\"opacity: 0;\" data-nosnippet=\"\">__IP__<\/span><\/p>\n<p>Ya con experiencia trabajando en Norteam\u00e9rica, en 2022 fue elegida como una de las nuevas caras en el remake de <strong>Pretty Little Liars <\/strong>en MAX, adentr\u00e1ndose en el g\u00e9nero de thriller de Hollywood. En cine, tuvo una breve participaci\u00f3n en <i>Do Revenge (Netflix)<\/i> y fue la protagonista de <i>A Cuban Girl\u2019s Guide to Tea and Tomorrow<\/i><span>.<\/span><\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-02\"\/><\/p>\n<p>Su extenso curr\u00edculum no se detiene ah\u00ed, ya que en 2024 protagoniz\u00f3 el musical ganador del Tony, <strong>Hadestown<\/strong><span>, en el papel de Eur\u00eddice. <\/span><a href=\"\/-agenciana_t6916e70a4551e78eb9423f59\"><span>#AgenciaNA<\/span><\/a><span>\u00a0<\/span><\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/01\/Quien-es-Maia-Reficco-la-actriz-que-estaria-en-pareja.jpeg\"><\/p>\n<p>Noticias Argentinas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 12 enero (NA) \u2013 La actriz Maia Reficco se convirti\u00f3 en tapa de portales al ser se\u00f1alada como la nueva pareja del piloto de F\u00f3rmula 1, Franco Colapinto, luego de que \u00e9l compartiera una foto de ella usando su casco. Los rumores se alimentaron cuando vieron que el corredor hab\u00eda parafraseado un posteo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":189956,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-189945","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/189945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=189945"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/189945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/189956"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=189945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=189945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=189945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}