{"id":185757,"date":"2026-01-05T08:03:22","date_gmt":"2026-01-05T11:03:22","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/leonardo-dicaprio-llego-a-los-critics-choice-awards-tras-quedar-varado-en-st-barts_a695b1f1fcbf033dd99dbde15\/"},"modified":"2026-01-05T08:03:22","modified_gmt":"2026-01-05T11:03:22","slug":"leonardo-dicaprio-llego-a-los-critics-choice-awards-tras-quedar-varado-en-st-barts_a695b1f1fcbf033dd99dbde15","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/leonardo-dicaprio-llego-a-los-critics-choice-awards-tras-quedar-varado-en-st-barts_a695b1f1fcbf033dd99dbde15\/","title":{"rendered":"Leonardo DiCaprio lleg\u00f3 a los Critics Choice Awards tras quedar varado en St. Barts"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/01\/Leonardo-DiCaprio-llego-a-los-Critics-Choice-Awards-tras-quedar.jpeg\" \/><\/p>\n<div itemprop=\"articleBody\">\n<p><a rel=\"noopener nofollow\" href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\"><strong>Buenos Aires, 4 de diciembre de 2026 (NA)&#8211; <\/strong><\/a><strong>Leonardo DiCaprio<\/strong> fue una de las grandes figuras de la noche en los <strong>Critics Choice Awards<\/strong>, pero su llegada estuvo marcada por un imprevisto que casi le impide asistir a la ceremonia.<\/p>\n<p>Seg\u00fan pudo constatar la <a rel=\"noopener nofollow\" href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\"><strong>Agencia Noticias Argentinas<\/strong><\/a><strong>, <\/strong>el actor <span>casi se pierde la premiaci\u00f3n despu\u00e9s de quedar<\/span> atrapado en St. Barts debido a un problema de control de tr\u00e1fico a\u00e9reo que afect\u00f3 al sur de California durante algunas horas.\u00a0<\/p>\n<p style=\"--ipspy: __IP__;color: __IP__;text-decoration: __IP__;\" alt=\"__IP__\" data-ipspy=\"__IP__\" title=\"__IP__\">El ganador del Oscar lleg\u00f3 justo a tiempo para que la presentadora <strong>Chelsea Handler<\/strong> se burlara de su susto durante su mon\u00f3logo de apertura.<strong>&#8220;Leo casi no sobrevive esta noche porque qued\u00f3 atrapado en un barco en St.<\/strong> <strong>Barts&#8221;<\/strong>, dijo y agreg\u00f3: <strong>&#8220;Fue como el Titanic, pero peor, porque Jeff Bezos estaba all\u00ed&#8221;<\/strong>.<span style=\"opacity: 0;\" data-nosnippet=\"\">__IP__<\/span><\/p>\n<p><tadevel-ad  class=\"block-4d\" slot-id=\"article-inline-01\"\/><\/p>\n<p><span>Tras pasar A\u00f1o Nuevo en el paradis\u00edaco lugar junto al fundador de Amazon y su esposa <\/span><strong>Lauren Sanchez Bezos, <\/strong><span>el actor tuvo que perderse el Festival Internacional de Cine de Palm Springs el 3 de enero a causa de ese incidente.<\/span><\/p>\n<p><a href=\"\/-agenciana_t6916e70a4551e78eb9423f59\">#AgenciaNA<\/a>\u00a0<\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/01\/1767611002_876_Leonardo-DiCaprio-llego-a-los-Critics-Choice-Awards-tras-quedar.jpeg\"><\/p>\n<p>Noticias Argentinas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 4 de diciembre de 2026 (NA)&#8211; Leonardo DiCaprio fue una de las grandes figuras de la noche en los Critics Choice Awards, pero su llegada estuvo marcada por un imprevisto que casi le impide asistir a la ceremonia. Seg\u00fan pudo constatar la Agencia Noticias Argentinas, el actor casi se pierde la premiaci\u00f3n despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":185768,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-185757","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/185757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=185757"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/185757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/185768"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=185757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=185757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=185757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}