{"id":185719,"date":"2026-01-04T20:18:08","date_gmt":"2026-01-04T23:18:08","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/la-nueva-funcion-de-chatgpt-que-le-permite-usar-spotify-uber-y-mas-aplicaciones\/"},"modified":"2026-01-04T20:19:30","modified_gmt":"2026-01-04T23:19:30","slug":"la-nueva-funcion-de-chatgpt-que-le-permite-usar-spotify-uber-y-mas-aplicaciones","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/la-nueva-funcion-de-chatgpt-que-le-permite-usar-spotify-uber-y-mas-aplicaciones\/","title":{"rendered":"La nueva funci\u00f3n de ChatGPT que le permite usar Spotify, Uber y m\u00e1s aplicaciones"},"content":{"rendered":"<p><\/p>\n<div>\t\t<!-- { REGION4 --> <\/p>\n<header class=\"news-headline\">\n<h2 class=\"news-headline__article-summary\">\t\t<\/h2>\n<p class=\"ignore-parser\">Un cambio que refuerza la idea de la IA como un centro de control unificado.<\/p>\n<\/header>\n<div class=\"detail-highlighted-multimedia content-protected-false\">\n<figure class=\"detail-highlighted-multimedia__figure\"><figcaption class=\"detail-highlighted-multimedia__figcaption\">  <\/figcaption><\/figure>\n<\/p><\/div>\n<article class=\"article-body article-body--first-paragraph content-protected-false\" data-td-script-src=\"https:\/\/www.ambito.com\/td\/modulos\/encuestas\/js\/function-embeds-min-version-1767499598.js\">\n<p><a href=\"https:\/\/www.ambito.com\/tecnologia\/la-personalizacion-chatgpt-y-como-hacerlo-mas-tu-estilo-n6228376\" target=\"_blank\" rel=\"follow\">OpenAI<\/a> present\u00f3 una actualizaci\u00f3n que <strong>ampl\u00eda de forma significativa las capacidades de ChatGPT<\/strong> y lo acerca a un rol mucho m\u00e1s activo. A partir de ahora,<strong> el asistente puede conectarse con aplicaciones externas y ejecutar acciones concretas en nombre del usuario<\/strong>, sin necesidad de salir del chat ni alternar entre pantallas.<\/p>\n<\/article>\n<section class=\"suscription-false printed-edition\" style=\"display:none\">\n<p> El contenido al que quiere acceder es exclusivo para suscriptores.<\/p>\n<p>  <span> <button type=\"button\" name=\"button\" class=\"subscribe-btn mercadopago-btn\">suscribirse<\/button><\/span>  <span class=\"btns\"><button type=\"button\" name=\"button\" class=\"subscribe-btn reload-login\"> ya estoy suscripto<\/button><\/span>  <\/p>\n<\/section>\n<article class=\"article-body article-body--second-paragraph content-protected-false\">\n<p>Esta nueva funci\u00f3n transforma la experiencia de uso, ya que <strong>ChatGPT deja de limitarse a responder consultas y pasa a interactuar directamente con servicios digitales<\/strong>. La integraci\u00f3n apunta a simplificar tareas cotidianas y a reducir el tiempo dedicado a operaciones repetitivas dentro de distintas plataformas.<\/p>\n<\/article>\n<section class=\"related-news\">\t\t<span class=\"related-news__title\">Informate m\u00e1s<\/span>\t\t<\/p>\n<div class=\"row row--eq-height\">\n<div class=\"col-12 col-md-6\">\n<article class=\"news-article news-article--landscape-news news-article--landscape-news\">\n<figure class=\"news-article__figure figure\">\t\t<a href=\"https:\/\/www.ambito.com\/tecnologia\/la-estrategia-starlink-mejorar-la-seguridad-espacial-n6230064\" target=\"\" title=\"\u00e1mbito.com | La estrategia de Starlink para mejorar la seguridad espacial\" alt=\"\u00e1mbito.com | La estrategia de Starlink para mejorar la seguridad espacial\" rel=\"noindex nofollow noreferrer\"><br \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/08\/Starlink-este-es-el-artefacto-FUNDAMENTAL-para-poder-obtener-conexion.jpg\" alt=\"Los cambios que aprob\u00f3 Elon Musk en Starlink.\u00a0\" title=\"Los cambios que aprob\u00f3 Elon Musk en Starlink.\u00a0\" width=\"93\" height=\"52\" class=\"news-article__figure-img figure-img img-fluid\"\/>\t\t<\/a><\/figure>\n<\/article><\/div>\n<div class=\"col-12 col-md-6\">\n<article class=\"news-article news-article--landscape-news news-article--landscape-news\">\n<figure class=\"news-article__figure figure\">\t\t<a href=\"https:\/\/www.ambito.com\/tecnologia\/las-cinco-mejores-ia-segun-la-propia-inteligencia-artificial-n6229070\" target=\"\" title=\"\u00e1mbito.com | Las cinco mejores IA, seg\u00fan la propia Inteligencia Artificial\" alt=\"\u00e1mbito.com | Las cinco mejores IA, seg\u00fan la propia Inteligencia Artificial\" rel=\"noindex nofollow noreferrer\"><br \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2025\/10\/1761779882_501_Esta-es-la-receta-mas-dificil-de-realizar-en-todo.jpg\" alt=\"Las caracter\u00edsticas de cada Inteligencia Artificial diferencian el mercado de las mismas, permitiendo lugar para todas en un mismo ecosistema digital.\" title=\"Las caracter\u00edsticas de cada Inteligencia Artificial diferencian el mercado de las mismas, permitiendo lugar para todas en un mismo ecosistema digital.\" width=\"93\" height=\"52\" class=\"news-article__figure-img figure-img img-fluid\"\/>\t\t<\/a><\/figure>\n<\/article><\/div>\n<\/div>\n<\/section>\n<article class=\"article-body article-body--third-paragraph content-protected-false\">\n<figure id=\"8106431-Libre-360021101_wrap\" class=\"embed_cont type_imagen\" contenteditable=\"false\">\n<p>Chat GPT estudiar juntos <span onclick=\"parent.parent.TinyMCETdcuerpo.preview_embed('8106431-Libre-360021101')\" class=\"embed_colapse less\" id=\"8106431-Libre-360021101_colapse\"\/>  <span onclick=\"parent.parent.TinyMCETdcuerpo.delete_embed('8106431-Libre-360021101')\" class=\"embed_delete less\" id=\"8106431-Libre-360021101_delete\"\/><\/p>\n<div id=\"8106431-Libre-360021101_content\" class=\"embed_content\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/01\/1767568687_783_La-nueva-funcion-de-ChatGPT-que-le-permite-usar-Spotify.jpg\" alt=\"\" title=\"\" width=\"690\" height=\"460\" id=\"8106431-Libre-360021101_embed\" crossorigin=\"anonymous\" fetchpriority=\"high\" decode=\"async\"\/><\/div><figcaption class=\"embed_wrapper-cont\">   <\/figcaption><\/figure>\n<h2>Las aplicaciones m\u00e1s populares que ya funcionan dentro de ChatGPT<\/h2>\n<p>Entre las primeras<strong> integraciones disponibles aparecen servicios ampliamente utilizados como Spotify, Uber, DoorDash, Canva y Booking.com.<\/strong> Estas aplicaciones pueden vincularse directamente con ChatGPT, para que el asistente ejecute acciones espec\u00edficas dentro de cada una.<\/p>\n<\/article>\n<article class=\"article-body article-body--fourth-paragraph content-protected-false\">\n<p>La conexi\u00f3n se realiza de manera guiada y sin pasos complejos:<\/p>\n<\/article>\n<article class=\"article-body article-body--fifth-paragraph content-protected-false\">\n<ul>\n<li aria-level=\"1\">\n<p>Al mencionar el nombre de la app dentro del chat, el sistema indica c\u00f3mo asociar la cuenta<\/p>\n<\/li>\n<li aria-level=\"1\">\n<p> Tambi\u00e9n existe la posibilidad de administrar todas las integraciones desde el men\u00fa de Configuraci\u00f3n, en la secci\u00f3n Aplicaciones y Conectores.<\/p>\n<\/li>\n<\/ul>\n<figure id=\"8171168-Libre-123340113_wrap\" class=\"embed_cont type_imagen\" contenteditable=\"false\">\n<p>l-chatgpt-app-photo-by-olivier-morin-afp-via-getty-images-r-spotify-logo-photo-by-emmanuel-dunand-afp-via-getty-images <span onclick=\"parent.parent.TinyMCETdcuerpo.preview_embed('8171168-Libre-123340113')\" class=\"embed_colapse less\" id=\"8171168-Libre-123340113_colapse\"\/>  <span onclick=\"parent.parent.TinyMCETdcuerpo.delete_embed('8171168-Libre-123340113')\" class=\"embed_delete less\" id=\"8171168-Libre-123340113_delete\"\/><\/p>\n<div id=\"8171168-Libre-123340113_content\" class=\"embed_content\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chacosintesis.com.ar\/wp-content\/uploads\/2026\/01\/La-nueva-funcion-de-ChatGPT-que-le-permite-usar-Spotify.webp\" alt=\"\" title=\"\" width=\"730\" height=\"365\" id=\"8171168-Libre-123340113_embed\"\/><\/div><figcaption class=\"embed_wrapper-cont\">   <\/figcaption><\/figure>\n<h2>Qu\u00e9 se puede hacer con las nuevas integraciones<\/h2>\n<p>Las funciones disponibles<strong> dependen de cada aplicaci\u00f3n<\/strong> conectada. <strong>En Spotify, ChatGPT permite crear playlists personalizadas,<\/strong> seg\u00fan el estado de \u00e1nimo o los h\u00e1bitos musicales. <strong>Uber facilita la b\u00fasqueda de opciones de traslado, <\/strong>sin necesidad de abrir la app.<\/p>\n<\/article>\n<article class=\"article-body article-body--remaining-paragraph content-protected-false\">\n<p><strong>El apartado creativo tambi\u00e9n suma protagonismo con herramientas como Canva,<\/strong> que permite dise\u00f1ar presentaciones, afiches o publicaciones para redes sociales a partir de simples descripciones.<strong> Figma, por su parte, se integra como una opci\u00f3n pr\u00e1ctica para crear diagramas y flujos de trabajo de forma r\u00e1pida y ordenada.<\/strong><\/p>\n<\/article>\n<p>\t\t\t\t<!-- REGION4 } -->\n\t\t\t\t\t\t<\/div>\n<p><script>\n!function(f,b,e,v,n,t,s)\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\nn.queue=[];t=b.createElement(e);t.async=!0;\nt.src=v;s=b.getElementsByTagName(e)[0];\ns.parentNode.insertBefore(t,s)}(window,document,'script',\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\nfbq('init', '2047048335588113');\nfbq('track', 'PageView');\n<\/script><\/p>\n<p>Ambito.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cambio que refuerza la idea de la IA como un centro de control unificado. OpenAI present\u00f3 una actualizaci\u00f3n que ampl\u00eda de forma significativa las capacidades de ChatGPT y lo acerca a un rol mucho m\u00e1s activo. A partir de ahora, el asistente puede conectarse con aplicaciones externas y ejecutar acciones concretas en nombre del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":185730,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[196],"tags":[],"class_list":["post-185719","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tecno"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/185719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=185719"}],"version-history":[{"count":1,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/185719\/revisions"}],"predecessor-version":[{"id":185731,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/185719\/revisions\/185731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/185730"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=185719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=185719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=185719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}