{"id":167647,"date":"2025-12-04T13:08:51","date_gmt":"2025-12-04T16:08:51","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/index.php\/resistencia-recuperan-herramientas-robadas-de-una-escuela-tecnica\/"},"modified":"2025-12-04T13:08:51","modified_gmt":"2025-12-04T16:08:51","slug":"resistencia-recuperan-herramientas-robadas-de-una-escuela-tecnica","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/resistencia-recuperan-herramientas-robadas-de-una-escuela-tecnica\/","title":{"rendered":"RESISTENCIA: Recuperan Herramientas Robadas De Una Escuela T\u00e9cnica"},"content":{"rendered":"<p><\/p>\n<p>Este mi\u00e9rcoles por la noche, efectivos de la Comisar\u00eda Sexta lograron recuperar varias herramientas que hab\u00edan sido robadas de la Escuela T\u00e9cnica ubicada sobre avenida Hernandarias.<\/p>\n<p>El procedimiento se inici\u00f3 luego de que la Comisar\u00eda Decimocuarta informara que un hombre estar\u00eda intentando vender elementos similares a los sustra\u00eddos. El personal se dirigi\u00f3 a la zona de Brasilia y Echeverr\u00eda, donde supuestamente merodeaba el sujeto. Si bien no pudieron localizarlo, durante el recorrido encontraron entre las malezas de un descampado dos buscapolos, un cos\u00edmetro y dos mult\u00edmetros.<\/p>\n<p>Todo lo recuperado fue secuestrado y puesto a disposici\u00f3n de la Fiscal\u00eda en turno, mientras los agentes contin\u00faan trabajando para identificar al responsable del hecho.<\/p>\n<p><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"[og_img]?w=75&resize=75&ssl=1 75w, [og_img]?w=100&resize=100&ssl=1 100w, [og_img]?w=150&resize=150&ssl=1 150w, [og_img]?w=240&resize=240&ssl=1 240w, [og_img]?w=320&resize=320&ssl=1 320w, [og_img]?w=500&resize=500&ssl=1 500w, [og_img]?w=640&resize=640&ssl=1 640w, [og_img]?w=800&resize=800&ssl=1 800w, [og_img]?w=1024&resize=1024&ssl=1 1024w, [og_img]?w=1280&resize=1280&ssl=1 1280w, [og_img]?w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"[og_img]\"><\/p>\n<p>Noticias del Paran\u00e1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles por la noche, efectivos de la Comisar\u00eda Sexta lograron recuperar varias herramientas que hab\u00edan sido robadas de la Escuela T\u00e9cnica ubicada sobre avenida Hernandarias. El procedimiento se inici\u00f3 luego de que la Comisar\u00eda Decimocuarta informara que un hombre estar\u00eda intentando vender elementos similares a los sustra\u00eddos. El personal se dirigi\u00f3 a la zona [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-167647","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-policiales"},"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/167647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=167647"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/167647\/revisions"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=167647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=167647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=167647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}