{"id":154554,"date":"2025-11-11T17:55:00","date_gmt":"2025-11-11T20:55:00","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=154554"},"modified":"2025-11-12T18:58:19","modified_gmt":"2025-11-12T21:58:19","slug":"saenz-pena-cultura-municipal-realizara-el-2-encuentro-provincial-de-folclore","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/saenz-pena-cultura-municipal-realizara-el-2-encuentro-provincial-de-folclore\/","title":{"rendered":"Saenz Pe\u00f1a: Cultura Municipal realizar\u00e1 el \u201c2\u00b0 Encuentro Provincial de Folclore\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En conferencia de prensa, las profesoras Silvia Sobol y Leonela Molnar, &nbsp;invitaron a la comunidad a participar del \u201c2\u00b0 Encuentro Provincial de Folclore\u201d, a realizarse en la Casa de la Cultura durante el s\u00e1bado 15 de noviembre. Donde participar\u00e1n m\u00e1s de 20 Academias pertenecientes a distintos puntos de la provincia y de Santiago del Estero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al brindar detalles de la organizaci\u00f3n de este evento cultural que se viene, algunas de las Academias confirmadas fueron La Providencia (Resistencia), Ra\u00edces de Amor (Pampa del Infierno), Orgullo Argentino, Tierra M\u00eda (Pampa de los Guanacos), &nbsp;Ra\u00edces de mi abuelo, Sol de Mi Tierra, Arbolada de mi Pa\u00f1uelo (Villa \u00c1ngela), Sol de mi Tierra (Santiago del Estero), El Algarrobo, El Pollito (ambas de S\u00e1enz Pe\u00f1a),entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El inicio de las actividades que tendr\u00e1 este evento ser\u00e1 a las 18 horas con un Desfile desde la Plaza Central&nbsp; hasta el Centro Cultural, en tanto que a las 19 ser\u00e1 la Gala con la presentaci\u00f3n de todas las Academias &nbsp;y luego actuar\u00e1n &#8220;Los Puntah&#8221;, Orejanos Folk y &#8220;Av\u00edo del Alma&#8221;.<br>El valor de las entradas anticipadas es de $5.000, que se pueden adquirir en Casa de Cultura, &nbsp;y en puerta estar\u00e1n a $7.000. Habr\u00e1 servicio de cantina y patio de emprendedores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conferencia de prensa, las profesoras Silvia Sobol y Leonela Molnar, &nbsp;invitaron a la comunidad a participar del \u201c2\u00b0 Encuentro Provincial de Folclore\u201d, a realizarse en la Casa de la Cultura durante el s\u00e1bado 15 de noviembre. Donde participar\u00e1n m\u00e1s de 20 Academias pertenecientes a distintos puntos de la provincia y de Santiago del Estero. [&hellip;]<\/p>\n","protected":false},"author":10001,"featured_media":154555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[628],"class_list":["post-154554","post","type-post","status-publish","format-standard","has-post-thumbnail","category-chaco","tag-saenzpena"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/154554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/10001"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=154554"}],"version-history":[{"count":1,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/154554\/revisions"}],"predecessor-version":[{"id":154556,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/154554\/revisions\/154556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/154555"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=154554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=154554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=154554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}