{"id":13284,"date":"2021-12-20T09:36:43","date_gmt":"2021-12-20T12:36:43","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=13284"},"modified":"2021-12-20T09:37:37","modified_gmt":"2021-12-20T12:37:37","slug":"il-divo-murio-el-cantante-carlos-marin-integrante-del-grupo-musical-de-opera","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/il-divo-murio-el-cantante-carlos-marin-integrante-del-grupo-musical-de-opera\/","title":{"rendered":"Il Divo: muri\u00f3 el cantante Carlos Mar\u00edn, integrante del grupo musical de \u00f3pera"},"content":{"rendered":"<div dir=\"ltr\">La banda anunci\u00f3 el fallecimiento de \u201csu amigo y socio\u201d a trav\u00e9s de las redes; \u201cSus amigos, familiares y fan\u00e1ticos lo extra\u00f1ar\u00e1n\u201d, aseguraron.<\/p>\n<p>\u201cCon gran pesar les hacemos saber que nuestro amigo y socio Carlos Mar\u00edn ha fallecido\u201d, inform\u00f3 esta tarde la banda Il Divo, al anunciar la muerte del integrante del grupo musical de \u00f3pera. \u201cSus amigos, familiares y fan\u00e1ticos lo extra\u00f1ar\u00e1n. Nunca habr\u00e1 otra voz o esp\u00edritu como Carlos\u201d, aseguraron.<\/p>\n<p>El cantante espa\u00f1ol Carlos Mar\u00edn, de 53 a\u00f1os, integrante del grupo brit\u00e1nico Il Divo, se encontraba internado en estado grave y coma inducido en el Royal Hospital de Manchester, Inglaterra, seg\u00fan medios de prensa de Galicia, donde la formaci\u00f3n iba a presentarse el 22 de diciembre.<\/p>\n<p>\u201cDurante 17 a\u00f1os, los cuatro hemos compartido este camino de Il Divo juntos, y extra\u00f1aremos a nuestro querido amigo. Esperamos y rezamos para que su hermosa alma descanse en paz\u201d, afirmaron sus compa\u00f1eros de grupo, David Miller, Sebastien Izambard y Urs B\u00fchler.<\/p>\n<p>El grupo tambi\u00e9n ten\u00eda planeado actuar el 8 de mayo de 2022 en el Luna Park de la ciudad de Buenos Aires y presentar su disco \u201cFor Once In My Life: A Celebration of Motown\u201d.<\/p>\n<p>Nacido en Alemania e hijo de espa\u00f1oles, Carlos Mar\u00edn comenz\u00f3 su carrera musical a los 12 a\u00f1os en Madrid en \u00f3peras y zarzuelas, hasta que en 2004 entr\u00f3 a formar parte de Il Divo, fundado por Simon Cowell, jurado de \u201cThe X-Factor\u201d; el cuarteto vendi\u00f3 hasta el momento m\u00e1s de 35 millones de discos en todo el mundo.<\/p>\n<p>Seg\u00fan trascendi\u00f3, Mar\u00edn se empez\u00f3 a sentir mal durante los \u00faltimos d\u00edas pero quer\u00eda seguir adelante con la gira por Gran Breta\u00f1a porque cre\u00eda que se recuperar\u00eda, pero el mi\u00e9rcoles tuvo que ser hospitalizado.<\/p>\n<p>Il Divo dio su \u00faltimo concierto en la localidad brit\u00e1nica de Bath el pasado 8 de diciembre. El grupo dio un mensaje en sus redes sociales anunciando que se suspender\u00edan las fechas pautadas para ese mes. \u201cDesafortunadamente, debido a una enfermedad, las fechas restantes de la gira de Il Divo en diciembre de 2021 por el Reino Unido se han pospuesto hasta diciembre de 2022. Il Divo se disculpa profundamente con sus fans, pero espera volver a los escenarios en el nuevo a\u00f1o\u201d.<\/p>\n<p>Carlos Mar\u00edn forma parte de Il Divo desde su formaci\u00f3n en 2003, junto al suizo Urs B\u00fchler, el estadounidense David Miller y el franc\u00e9s S\u00e9bastien Izambard.<\/p>\n<p>Con nueve \u00e1lbumes de estudio y un \u00e9xito conseguido a nivel mundial, la banda es considerada una de las precursoras en la popularizaci\u00f3n de la m\u00fasica cl\u00e1sica. En solitario, Mar\u00edn public\u00f3 en 2021 un disco en solitario titulado Portrait en el que hizo su versi\u00f3n de Bohemian Rhapsody de Queen, entre otros grandes \u00e9xitos.<\/p>\n<p>La noticia de su muerte sorprendi\u00f3 por completo a sus fans. Desde su internaci\u00f3n, en las redes sociales no cesaron los mensajes de aliento para el artista y su familia.<\/p>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La banda anunci\u00f3 el fallecimiento de \u201csu amigo y socio\u201d a trav\u00e9s de las redes; \u201cSus amigos, familiares y fan\u00e1ticos lo extra\u00f1ar\u00e1n\u201d, aseguraron. \u201cCon gran pesar les hacemos saber que nuestro amigo y socio Carlos Mar\u00edn ha fallecido\u201d, inform\u00f3 esta tarde la banda Il Divo, al anunciar la muerte del integrante del grupo musical de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-13284","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13284"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13285"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}