{"id":12104,"date":"2021-09-28T09:45:40","date_gmt":"2021-09-28T12:45:40","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=12104"},"modified":"2021-09-28T10:07:13","modified_gmt":"2021-09-28T13:07:13","slug":"capitanich-anuncio-aumento-para-estatales-descuentos-en-supermercados-creditos-para-viviendas-y-actividades-afectadas-por-la-pandemia","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/capitanich-anuncio-aumento-para-estatales-descuentos-en-supermercados-creditos-para-viviendas-y-actividades-afectadas-por-la-pandemia\/","title":{"rendered":"Capitanich anunci\u00f3 aumento para estatales, descuentos en supermercados, cr\u00e9ditos para viviendas y actividades afectadas por la pandemia"},"content":{"rendered":"<div dir=\"ltr\">El gobernador Jorge Capitanich anunci\u00f3 en la ma\u00f1ana de este martes una serie de medidas econ\u00f3micas, que implican una inversi\u00f3n para el Estado provincial equivalente a los 4 mil millones de pesos, que apuntan a mejorar los ingresos de la ciudadan\u00eda, facilitar la construcci\u00f3n de viviendas y recuperar a los sectores m\u00e1s afectados por la pandemia.<\/p>\n<p>Capitanich, acompa\u00f1ado por la vicegobernadora Analia Rach Quiroga, ministros de distintas \u00e1reas y autoridades de entidades y organismos estatales, asever\u00f3 que como consecuencia de la pandemia huco ciertas restricciones que impidieron la cercan\u00eda con la gente, y que en esta etapa de Gobierno \u201cse profundizar\u00e1 m\u00e1s el contacto y el trabajo mancomunado con nuestra comunidad\u201d.<\/p>\n<p>Anuncios en materia de precios<\/p>\n<p>Como primer punto el gobernador anunci\u00f3 una serie de medidas referidas al precio de alimentos. Explic\u00f3 que \u201cuna de las demandas m\u00e1s importantes pasa porque la plata, y es por ello que desde la provincia vamos a acompa\u00f1ar las medidas adoptadas por Naci\u00f3n mediante un acuerdo con los empresarios de la provincia del Chaco para establecer los precios acordados por 25 productos, que incluye a los ya puestos en marcha como ser carne y panificaci\u00f3n\u201d. En el caso del pan se estableci\u00f3 que el precio de referencia quedar\u00e1 fijo hasta el 31 de diciembre.<\/p>\n<p>\u201cAmbos acuerdos contar\u00e1n con un control estricto por parte del Estado provincial para que el compromiso entre el sector privado y el sector p\u00fablico se concrete en las g\u00f3ndolas\u201d, dijo el gobernador.<\/p>\n<p>Otra de las medidas beneficia a quienes tengan Tarjeta Tuya, ya que todos los mi\u00e9rcoles tendr\u00e1n descuentos de 50% en los supermercados, con un tope de reintegro de hasta 4 mil pesos. Adem\u00e1s todos los martes tendr\u00e1n descuentos de 30% en farmacias, con un tope de reintegro de hasta 2 mil pesos.<\/p>\n<p>Beneficios para construcci\u00f3n de viviendas<\/p>\n<p>El gobernador anunci\u00f3 adem\u00e1s que continuar\u00e1n los cr\u00e9ditos bancarios del Nuevo Banco del Chaco para refacciones. Asever\u00f3 que quienes quieran refaccionar sus viviendas, tendr\u00e1n acceso a un tercer tramo de l\u00ednea de cr\u00e9dito para la compra de materiales de construcci\u00f3n y afines. Vale mencionar que para esta nueva edici\u00f3n la l\u00ednea de cr\u00e9dito dispondr\u00e1 de un volumen total 1.000 millones de pesos.<\/p>\n<p>Anticip\u00f3 tambi\u00e9n que se relanzar\u00e1 el programa Vivienda Adecuada que brinda una serie de cr\u00e9ditos no bancarios subsidiados a trav\u00e9s de una tarjeta recargable del NBCh en la que cada beneficiario deber\u00e1 devolver $30 de cada $100 prestados por el Estado. La l\u00ednea dispondr\u00e1 de 500 millones de pesos.<\/p>\n<p>Tambi\u00e9n se instrumentar\u00e1 la entrega de Tarjeta Tuya para las Organizaciones de la Sociedad Civil. Se estima que se beneficiar\u00e1n 500 Organizaciones las cuales percibir\u00e1n hasta 500 mil pesos, los cuales deber\u00e1n ser destinados a la compra de materiales de construcci\u00f3n para refaccionar clubes de barrio, centros culturales, bibliotecas, comedores y distintas instituciones que brindan servicios b\u00e1sicos para la comunidad.Adem\u00e1s detall\u00f3 que se continuar\u00e1 con el programa \u201cMejor techo, Mejor Vida\u201d el cual brinda un aporte no reintegrable de emergencia para familias de extrema vulnerabilidad que viven en condiciones de precariedad habitacional. El beneficio ir\u00e1 desde 100.000 a 300.000 pesos y financiar\u00e1 tanto la compra de materiales como la mano de obra.<\/p>\n<p>En esta materia Capitanich anunci\u00f3:<\/p>\n<p>\u00a0<\/p>\n<p>Moratoria: plan de facilidad de pagos para PyMEs con tasa de hasta 0% y condonaci\u00f3n de intereses punitorios de hasta el 100%.<br \/>Cr\u00e9ditos tasa 0% para Comercio, Turismo y Gastronom\u00eda con 3 meses de gracia y por un monto de hasta $350.000.<br \/>Programa de recuperaci\u00f3n de empresas \u201cRecuperar MiPyME\u201d: l\u00ednea de cr\u00e9dito y postergaci\u00f3n de impuestos provinciales para empresas que hayan cerrado entre abril de 2020 y junio de 2021 producto de la pandemia, a tasa 0% y con un periodo de gracia de 6 a 9 meses.<br \/>Polo socio-productivo: con el objetivo de vincular los planes sociales con el empleo de calidad, el Estado pondr\u00e1 a disposici\u00f3n de emprendedores sociales un espacio f\u00edsico para que accedan a un espacio de trabajo digno, con herramientas, m\u00e1quinas, insumos y materiales. Los destinatarios ser\u00e1n los beneficiarios de los programas \u201cPotenciar Trabajo\u201d y \u201cRenta M\u00ednima Progresiva\u201d y las actividades involucradas ser\u00e1n Textil, Econom\u00eda Circular y Oficios (herrer\u00eda, carpinter\u00eda, electricidad<\/p>\n<p>\u00a0<\/p>\n<p>Beneficio para agentes p\u00fablicos<\/p>\n<p>Referido a las trabajadoras y los trabajadores de la administraci\u00f3n p\u00fablica el gobernador anuncio un aumento general de 7% a la escala salarial para toda la planta de la administraci\u00f3n; la instrumentaci\u00f3n de un Bono 10.000 pesos para todos los trabajadores de la administraci\u00f3n p\u00fablica pagadero en octubre.<\/p>\n<p>Tambi\u00e9n anticip\u00f3 que en octubre se realizar\u00e1 el pago de cl\u00e1usula gatillo para todos los docentes, que rondar\u00e1 8% de acuerdo a la inflaci\u00f3n del tercer trimestre del a\u00f1o. Esto implica un aumento aproximado de 15% para cada docente.<\/p>\n<p>Respecto al Programa Expertos, y en l\u00ednea con el aumento del Salario M\u00ednimo Vital y m\u00f3vil, se incrementar\u00e1 a partir del 1\u00b0 de septiembre a $31.104, a partir del 1\u00b0 de octubre $32.000 y a partir del 1\u00b0 de febrero $33.000.<\/p>\n<p>Los jornalizados tendr\u00e1n un un aumento de 25% en el valor del jornal, lo cual significa una recomposici\u00f3n superior al 60% en lo que va de 2021 para aquellas trabajadoras y trabajadores con menores salarios dentro de la administraci\u00f3n p\u00fablica.<\/p>\n<p>Respecto a los profesionales que no se encuentran en planta permanente se avanzar\u00e1 en un pase a contrato de servicio para todos los profesionales y aquellos que tengan m\u00e1s de 10 a\u00f1os de antig\u00fcedad (Ej: Expertos, M\u00e9dicos Comunitarios y Contrataciones Directas).<\/p>\n<div><\/div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Jorge Capitanich anunci\u00f3 en la ma\u00f1ana de este martes una serie de medidas econ\u00f3micas, que implican una inversi\u00f3n para el Estado provincial equivalente a los 4 mil millones de pesos, que apuntan a mejorar los ingresos de la ciudadan\u00eda, facilitar la construcci\u00f3n de viviendas y recuperar a los sectores m\u00e1s afectados por la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12105,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[60],"class_list":["post-12104","post","type-post","status-publish","format-standard","has-post-thumbnail","category-chaco","tag-featured"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12104"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12105"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}