{"id":12085,"date":"2021-09-26T12:04:58","date_gmt":"2021-09-26T15:04:58","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=12085"},"modified":"2021-09-26T12:06:43","modified_gmt":"2021-09-26T15:06:43","slug":"coronavirus-la-provincia-flexibiliza-medidas-sanitarias","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/coronavirus-la-provincia-flexibiliza-medidas-sanitarias\/","title":{"rendered":"Coronavirus: la provincia flexibiliza medidas sanitarias"},"content":{"rendered":"<div dir=\"ltr\">Por la importante reducci\u00f3n de la cantidad de casos de coronavirus y el avance del plan de vacunaci\u00f3n, el Gobierno provincial, en concordancia con Naci\u00f3n, deja sin efecto la obligatoriedad del uso de barbijo al aire libre, excepto en aquellos casos con aglomeraci\u00f3n de personas. Ser\u00e1 obligatorio contar con &quot;Pasaporte Chaco&quot; para circular.<\/p>\n<p>Mediante el Decreto Provincial N\u00b0 2071, y teniendo en cuenta la importante reducci\u00f3n de casos positivos, as\u00ed como el avance del plan de vacunaci\u00f3n, el Gobierno estableci\u00f3 las medidas de bioseguridad vigentes a partir del 26 de septiembre del corriente, en el marco de la pandemia por Covid-19. Entre ellas se destaca que queda sin efecto el uso obligatorio de barbijos o tapabocas al aire libre, excepto en aquellos casos en que hubiera aglomeraci\u00f3n de personas, entre ellos el transporte p\u00fablico de pasajeros.<\/p>\n<p>Asimismo, tambi\u00e9n se establece la obligatoriedad de cumplir con los protocolos vigentes en el desarrollo de actividades, el distanciamiento social y el uso continuo de alcohol en gel, ventilaci\u00f3n de ambientes y desinfecci\u00f3n de superficies, elementos y espacios de uso comunitario.<\/p>\n<p>Modalidades y reglas particulares para el desarrollo de actividades<\/p>\n<p>Reuniones, eventos, actos y celebraciones: contin\u00faa habilitado el desarrollo de los mismos, incluyendo domicilios particulares. Al aire libre el aforo ser\u00e1 del 100%, en tanto que los eventos en espacios cerrados se encuentran habilitados exclusivamente para personas que cuenten con Pasaporte Chaco en estado verde al 100% del aforo disponible de cada espacio.<\/p>\n<p>Casinos, cines, teatros y auditorios: se encuentra habilitado su funcionamiento al 100 % del aforo disponible para personas que cuenten con Pasaporte Chaco en estado verde.<\/p>\n<p>Actividad comercial, industrial, profesional y de servicios: se encuentran habilitadas al 100 % del aforo disponible de cada espacio, incluy\u00e9ndose locales de centros comerciales, shopping, call centers.<\/p>\n<p>Gastronom\u00eda, restaurantes y bares: Se encuentran habilitados para su funcionamiento en espacios al aire libre y en espacios cerrados. El uso de los aforos en espacios cerrados, se permite exclusivamente para personas con Pasaporte Chaco en estado verde.<\/p>\n<p>Discotecas: Se habilita su funcionamiento con reducci\u00f3n de aforo al 50 % para concurrencia de personas que cuenten con Pasaporte Chaco en estado verde.<\/p>\n<p>Gimnasios, clubes, actividades f\u00edsicas y deportivas: Se ratifican disposiciones del Decreto 1581.<\/p>\n<p>Iglesias, cultos y celebraciones religiosas: Se ratifican disposiciones del Decreto 1581.<\/p>\n<p>Plazas, parques y parques recreativos: El uso de dichos espacios se encuentra habilitado para el desarrollo de actividades. La autoridad de aplicaci\u00f3n podr\u00e1 disponer los procedimientos, controles y\/o desalojos que resulten necesarios a efectos de evitar aglomeraciones de personas, en forma coordinada con la Polic\u00eda de la Provincia, guardias comunitarias y agentes municipales.<\/p>\n<p>Transporte: Se ratifica la capacidad de ocupaci\u00f3n habilitada del cien por ciento (100%) de cada unidad con uso de tapabocas obligatorio. Excepcionalmente en los horarios de mayor requerimiento del servicio y ante el exceso en la demanda, la capacidad podr\u00e1 ampliarse hasta veinte (20) pasajeros de pie, de conformidad a los protocolos respectivos.<\/p>\n<p>Turismo: Se encuentra habilitado el transporte automotor tur\u00edstico y los viajes grupales de acuerdo a las medidas que a tales fines establezca la autoridad sanitaria y migratoria nacional. Las mismas se encuentran sujetas a las modificaciones que pudieran resultar necesarias conforme los indicadores sanitarios correspondientes.<\/p>\n<p>Peloteros y\/o espacios de recreaci\u00f3n infantil: Est\u00e1n habilitados para su funcionamiento sin restricciones en espacios al aire libre; en tanto que, en espacios cerrados, sin restricci\u00f3n de aforos, exclusivamente para personas con Pasaporte Chaco en estado verde.<\/p>\n<p>Sistema Educativo Provincial: Se ratifica la modalidad presencial como regla general.<\/p>\n<p>\u00a0<\/p>\n<p>Administraci\u00f3n P\u00fablica Provincial<\/p>\n<p>\u00a0<\/p>\n<p>El nuevo decreto ratifica las medidas que propicien la realizaci\u00f3n de trabajo remoto en todas aquellas \u00e1reas y\/o actividades que as\u00ed lo permitan.<\/p>\n<p>Se ratifican los turnos de trabajo rotativos y\/o alternados, matutinos y vespertinos, debiendo cumplirse en cualquiera de los casos las medidas de distanciamiento y ventilaci\u00f3n de espacios disponibles de cada oficina, repartici\u00f3n y\/o dependencia.<\/p>\n<p>Se dispone tambi\u00e9n que las autoridades jurisdiccionales respectivas podr\u00e1n convocar, de acuerdo a los requerimientos y necesidades de cada servicio, al retorno a la actividad laboral de manera presencial de las trabajadoras y los trabajadores que hubieran recibido al menos la primera dosis de cualquiera de las vacunas destinadas a generar inmunidad adquirida contra el Covid-19, independientemente de la edad y la condici\u00f3n de riesgo, transcurridos 14 d\u00edas de la inoculaci\u00f3n; con excepci\u00f3n de los siguientes casos:<\/p>\n<p>*Las y los agentes p\u00fablicos de todas las jurisdicciones, organismos y reparticiones mayores de 60 a\u00f1os y\/o pertenecientes a grupos de riesgo, que por las necesidades del servicio y\/o de la capacidad en los lugares destinados a la prestaci\u00f3n de los mismos se considere necesario mantener dispensados de asistencia presencial. As\u00ed como las personas con inmunodeficiencias.<\/p>\n<p>Ingreso y circulaci\u00f3n: se ratifican los requisitos de ingreso y circulaci\u00f3n en la Provincia, la utilizaci\u00f3n del Pasaporte Chaco, el cual se complementar\u00e1 con el sistema de Mi Argentina, plataforma digital que opera como documento oficial de acreditaci\u00f3n del esquema de vacunaci\u00f3n.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por la importante reducci\u00f3n de la cantidad de casos de coronavirus y el avance del plan de vacunaci\u00f3n, el Gobierno provincial, en concordancia con Naci\u00f3n, deja sin efecto la obligatoriedad del uso de barbijo al aire libre, excepto en aquellos casos con aglomeraci\u00f3n de personas. Ser\u00e1 obligatorio contar con &quot;Pasaporte Chaco&quot; para circular. Mediante el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[60],"class_list":["post-12085","post","type-post","status-publish","format-standard","has-post-thumbnail","category-chaco","tag-featured"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12085"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12086"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}