{"id":11951,"date":"2021-09-16T19:04:41","date_gmt":"2021-09-16T22:04:41","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=11951"},"modified":"2021-09-16T19:06:44","modified_gmt":"2021-09-16T22:06:44","slug":"abel-pintos-agoto-doce-funciones-en-el-movistar-arena-y-presento-un-nuevo-videoclip","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/abel-pintos-agoto-doce-funciones-en-el-movistar-arena-y-presento-un-nuevo-videoclip\/","title":{"rendered":"Abel Pintos agot\u00f3 doce funciones en el Movistar Arena y present\u00f3 un nuevo videoclip"},"content":{"rendered":"<div dir=\"ltr\">El cantautor presentar\u00e1 en vivo su \u00faltimo \u00e1lbum &quot;El amor de mi vida&quot; entre el 14 y el 31 de octubre, y lanz\u00f3 &quot;Espejo&quot;, el videoclip al que describi\u00f3 como una &quot;canci\u00f3n liberadora&quot;.<\/p>\n<p>El cantautor Abel Pintos, que acaba de agotar doce funciones para presentar en vivo en el Movistar Arena su \u00faltimo \u00e1lbum &quot;El amor de mi vida&quot;, lanz\u00f3 el videoclip del tema &quot;Espejo&quot;, al que describi\u00f3 como una &quot;canci\u00f3n liberadora&quot;.<\/p>\n<p>De esta manera, el artista mantiene en alto la expectativa de sus seguidores, quienes aguardan el esperado reencuentro en vivo por primera vez desde el inicio de la pandemia de coronavirus, el cual se producir\u00e1 entre el 14 y el 31 de octubre, en doce fechas previstas en el estadio Movistar Arena, con la excusa de mostrar el material de &quot;El amor de mi vida&quot;.<\/p>\n<p>En esta producci\u00f3n, su duod\u00e9cimo \u00e1lbum, el cantautor nacido en Bah\u00eda Blanca por primera vez se asoma a un repertorio que compuso y produjo con artistas iberoamericanos en una experiencia que, seg\u00fan dijo a T\u00e9lam en mayo pasado, le permiti\u00f3 &quot;llegar a un determinado lugar por medio de otro camino&quot;.<\/p>\n<p>&quot;Ten\u00eda muy en claro las cosas que necesitaba decir y arm\u00e9 un mapa muy claro con esos nombres a los que me abr\u00ed porque confiaba que iban a ser los indicados&quot;, se\u00f1al\u00f3 en ese momento.<\/p>\n<p>La galer\u00eda de colaboraciones para la placa la integran, adem\u00e1s de su hermano Ariel, desde Espa\u00f1a Vanesa Mart\u00edn, Beatriz Luengo y Diego Cantero; desde Puerto Rico Kany Garc\u00eda y Tommy Torres, el venezolano d\u00fao San Luis y el peruano Gian Marco Zignano.<\/p>\n<p>Adem\u00e1s, el cubano Yotuel Romero (ex Orishas), el mexicano Mario Domm (de Camila) y el argentino Nano Novello participaron como autores y productores sum\u00e1ndose en este \u00faltimo rol a Ettore Grenci, Juan Pablo Vega y Eduardo Cabra (ex Calle 13).<\/p>\n<p>Despu\u00e9s del \u00e9xito del single &quot;De mi contigo&quot;, que integr\u00f3 el top 5 en radios durante m\u00e1s de tres semanas consecutivas, ahora Pintos presenta el videoclip de &quot;Espejo&quot;, realizado por la agencia Soul Sister y la productora La Casa de Al Lado, y dirigido por Tom\u00e1s Curland y Bruno Adamovsky.<\/p>\n<div><\/div>\n<div>Telam.-<\/div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El cantautor presentar\u00e1 en vivo su \u00faltimo \u00e1lbum &quot;El amor de mi vida&quot; entre el 14 y el 31 de octubre, y lanz\u00f3 &quot;Espejo&quot;, el videoclip al que describi\u00f3 como una &quot;canci\u00f3n liberadora&quot;. El cantautor Abel Pintos, que acaba de agotar doce funciones para presentar en vivo en el Movistar Arena su \u00faltimo \u00e1lbum &quot;El [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-11951","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farandula"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11951"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11952"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}