{"id":11941,"date":"2021-09-16T10:11:10","date_gmt":"2021-09-16T13:11:10","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=11941"},"modified":"2021-09-16T10:36:46","modified_gmt":"2021-09-16T13:36:46","slug":"en-plena-crisis-guzman-envio-al-congreso-el-presupuesto","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/en-plena-crisis-guzman-envio-al-congreso-el-presupuesto\/","title":{"rendered":"En plena crisis, Guzm\u00e1n envi\u00f3 al Congreso el Presupuesto"},"content":{"rendered":"<div dir=\"ltr\">Prev\u00e9 un crecimiento del PBI de 4%, inflaci\u00f3n del 33% y un d\u00f3lar a $131.<\/p>\n<p>El proyecto del Presupuesto 2022 prev\u00e9 un crecimiento del 4% del Producto Bruto Interno, una inflaci\u00f3n del 33% y un d\u00f3lar a $131,1, pero adem\u00e1s no contempla el pago de vencimientos de capital al FMI, prev\u00e9 un incremento real del gasto social y una reducci\u00f3n de los subsidios energ\u00e9ticos.<\/p>\n<p>Ingres\u00f3 minutos antes de la medianoche del mi\u00e9rcoles al Parlamento para su tratamiento, tras la firma del presidente Alberto Fern\u00e1ndez y del ministro de Econom\u00eda, Mart\u00edn Guzm\u00e1n, y sus estimaciones anticipan el esquema de pol\u00edticas macroecon\u00f3micas, fiscal y cambiarias asociadas que pretende llevar adelante el Gobierno nacional.<\/p>\n<p>Entre los supuestos sobresalientes se destaca que la econom\u00eda crecer\u00e1 en 2022 un 4%, la mitad de lo previsto para este a\u00f1o, con lo cual se sobrepasar\u00e1 el nivel de actividad de la prepandemia, ya que terminar\u00e1 de compensar la retracci\u00f3n del 9,9% del 2020.<\/p>\n<p>En cuanto a la inflaci\u00f3n, el Ministerio de Econom\u00eda la estim\u00f3 en 33%, es decir 12 puntos porcentuales debajo de la previsi\u00f3n para el cierre de 2020, que debi\u00f3 ser revisada al alza promediando el primer semestre ya que el presupuesto en curso la ubicaba en un 29%.<\/p>\n<p>Las proyecciones para el pr\u00f3ximo a\u00f1o se complementan con alzas en el consumo privado del 4,6%, del consumo p\u00fablico del 3,1%, de la inversi\u00f3n del 6,6%, con una mejora de las exportaciones del 7,5% y de las importaciones del 9,4% para un saldo comercial de US$ 9.300 millones y con un tipo de cambio nominal de $131,1 por d\u00f3lar para diciembre 2022.<\/p>\n<p>Fuentes del Gobierno nacional explicaron que de esta manera la econom\u00eda estar\u00eda en la v\u00eda de la &quot;doble recuperaci\u00f3n&quot; que llevar\u00eda a la actividad a fines de 2023 a niveles similares de producto previo a la crisis macroecon\u00f3mica de la gesti\u00f3n Cambiemos en 2018, es decir del \u00faltimo trimestre de 2017.<\/p>\n<p>El trabajo contempla la actualizaci\u00f3n del escenario 2021 que de acuerdo a las &quot;proyecciones presupuestarias conservadoras&quot; preve\u00eda para este a\u00f1o un crecimiento de 5,5% del PBI pero que ahora se ratifica crecer\u00e1 en torno al 8%, con el consumo privado de un 9%, consumo p\u00fablico 5,2% y la inversi\u00f3n 31,1%.<\/p>\n<p>A la vez el cierre fiscal actualizado prev\u00e9 para 2021 una inflaci\u00f3n de 45,1% frente al 29% inicial, sensiblemente afectado por el incremento de comienzos de a\u00f1o de los precios internacionales de los commodities; un tipo de cambio que alcanzar\u00e1 seg\u00fan lo previsto los $102,4, as\u00ed como un aumento de las exportaciones del 12,2%, con un saldo comercial de 12.876 US$ millones.<\/p>\n<p>Este presupuesto con un rojo del 4,9% se financiar\u00e1 con una combinaci\u00f3n del cr\u00e9dito y financiamiento del banco Central.<\/p>\n<p>Este presupuesto con un rojo del 4,9% se financiar\u00e1 con una combinaci\u00f3n del cr\u00e9dito y financiamiento del banco Central.<\/p>\n<p>En cuanto a la evoluci\u00f3n de los salarios formales, el Gobierno entiende que el salario real continuar\u00e1 recuper\u00e1ndose que a septiembre de 2021 alcanza una mejora del 2,2% del RIPTE, y se apunta a un crecimiento del 4% interanual para 2022, entendiendo que habr\u00e1 a\u00fan dificultades con los ingresos informales afectados por la heterogeneidad de la recuperaci\u00f3n.<\/p>\n<p>En cuanto a las definiciones de la pol\u00edtica fiscal, el proyecto prev\u00e9 un escenario para 2021 de un d\u00e9ficit primario de 4% del PBI y un d\u00e9ficit financiero del 5,4%, pero con la aclaraci\u00f3n de que hay partidas subejecutadas que buscar\u00e1n acelerarse en lo que resta del actual per\u00edodo mediante un conjunto de medidas que se anunciar\u00e1n en breve.<\/p>\n<p>Para apuntalar la recuperaci\u00f3n de la econom\u00eda, el Ministerio de Econom\u00eda considera necesaria corregir esa ejecuci\u00f3n menor a la presupuestada para fortalecer la demanda agregada, para darle el nivel expansivo a la pol\u00edtica fiscal en la magnitud inicial.<\/p>\n<p>As\u00ed para 2022, se plantea un d\u00e9ficit primario del 3,3% y un resultado financiero del 4.9% del producto, algo mucho menor de lo que ser\u00eda sino se hubiera concretado la reestructuraci\u00f3n de la deuda en 2020 y que explica el nivel de reducci\u00f3n del d\u00e9ficit junto a la recuperaci\u00f3n de los ingresos fiscales.<\/p>\n<p>Este presupuesto con un rojo del 4,9% se financiar\u00e1 con una combinaci\u00f3n del cr\u00e9dito y financiamiento del banco Central que para 2021 fue de 3,6% del producto pero que para el pr\u00f3ximo a\u00f1o se reducir\u00e1 al 1,8%, es decir una reducci\u00f3n a la mitad, en tanto que los t\u00edtulos p\u00fablicos aportar\u00e1n un 2% del producto.<\/p>\n<p>Se consolida as\u00ed, a criterio del Ministerio de Econom\u00eda, una pol\u00edtica fiscal m\u00e1s apropiada para la recuperaci\u00f3n econ\u00f3mica con un financiamiento en pesos en el mercado de capitales y mayor dinamismo productivo, mejora infraestructura pero al mismo tiempo fortaleciendo la capacidad del Estado y las condiciones que dan lugar a la estabilidad macroecon\u00f3mica.<\/p>\n<p>En cuanto al desagregado de los distintos tributos se prev\u00e9 una mejora sustancial en t\u00e9rminos reales con una inflaci\u00f3n al 33%, en buena medida asociada a una recuperaci\u00f3n de la actividad econ\u00f3mica que impacta en \u00edtems como ganancias, IVA o los tributos de la seguridad social.<\/p>\n<p>En cuanto al gasto se explica que el conjunto de pilares estrat\u00e9gicos en los cuales el Estado juega rol clave en infraestructura, la salud, la educaci\u00f3n, la ciencia y educaci\u00f3n y las pol\u00edticas de protecci\u00f3n social activa con perspectiva de g\u00e9nero en un contexto de dificultades.<\/p>\n<p>Como rese\u00f1a los gastos en infraestructura se incrementan a 2,4% del producto; en salud el 0,65% en contexto de la pandemia; educaci\u00f3n 1,2%, en ciencia y educaci\u00f3n 0,31% y el presupuesto de inclusi\u00f3n social activa que llegar\u00e1 1,22%<\/p>\n<p>Finalmente, en materia de subsidios energ\u00e9ticos se proyecta un gasto sobre producto de 1,5%.<\/p>\n<p>Las fuentes del Ministerio de Econom\u00eda se\u00f1alaron que la Resoluci\u00f3n 46 de incentivo a la producci\u00f3n de gas que dispuso la gesti\u00f3n Cambiemos caduca en 2022 y al haber un Plan Gas con un valor vigente mucho m\u00e1s bajo reducir\u00e1 autom\u00e1ticamente los subsidios al 1,8% del producto.<\/p>\n<p>Pero, adicionalmente, se buscar\u00e1 llegar a un nivel de subsidios de 1,5% sobre el producto mediante la segmentaci\u00f3n de las tarifas que analiza a trav\u00e9s de la Secretar\u00eda de Energ\u00eda.<\/p>\n<p>CADENA 3.-<\/p>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prev\u00e9 un crecimiento del PBI de 4%, inflaci\u00f3n del 33% y un d\u00f3lar a $131. El proyecto del Presupuesto 2022 prev\u00e9 un crecimiento del 4% del Producto Bruto Interno, una inflaci\u00f3n del 33% y un d\u00f3lar a $131,1, pero adem\u00e1s no contempla el pago de vencimientos de capital al FMI, prev\u00e9 un incremento real del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[60],"class_list":["post-11941","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-featured"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11941"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11942"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}