{"id":11781,"date":"2021-09-07T09:17:39","date_gmt":"2021-09-07T12:17:39","guid":{"rendered":"https:\/\/chacosintesis.com.ar\/?p=11781"},"modified":"2021-09-07T09:37:37","modified_gmt":"2021-09-07T12:37:37","slug":"la-bajante-historica-del-parana-continua-impidiendo-la-navegacion","status":"publish","type":"post","link":"https:\/\/chacosintesis.com.ar\/index.php\/la-bajante-historica-del-parana-continua-impidiendo-la-navegacion\/","title":{"rendered":"La bajante hist\u00f3rica del Paran\u00e1 contin\u00faa impidiendo la navegaci\u00f3n"},"content":{"rendered":"<div dir=\"ltr\">La log\u00edstica en el puerto de Barranqueras, por camiones y trenes. Se profundiza una crisis que lleva m\u00e1s de un a\u00f1o. El pron\u00f3stico no es alentador.<\/p>\n<p>El r\u00edo Paran\u00e1 con el hidr\u00f3metro en Barranqueras contin\u00faa registrando n\u00fameros poco alentadores, en una bajante hist\u00f3rica, sostenida en el tiempo por hace m\u00e1s de un a\u00f1o.<br \/>Y el horizonte tampoco es muy positivo. Con la baja probabilidad de precipitaciones la situaci\u00f3n a estirarse a\u00fan m\u00e1s.<\/p>\n<p>Seg\u00fan asegur\u00f3 a NORTE, el vocal de la Administraci\u00f3n Provincial del Agua (APA), Gustavo D\u2019Alessandro, el Instituto Nacional del Agua prev\u00e9 para el 7 de septiembre una altura de 1,51 metros en el hidr\u00f3metro de Barranqueras, y 1,20 metros para el 14 de septiembre, continuando la tendencia bajista. Ayer el registro fue de 1,16 metros.<\/p>\n<p>Este contexto causa problemas, entre ellos, la dificultad de que la navegaci\u00f3n contin\u00fae dinamizando la econom\u00eda chaque\u00f1a.<\/p>\n<p>Es que seg\u00fan expuso a este medio Roberto Ben\u00edtez, titular del puerto de Barranqueras, hace m\u00e1s de un a\u00f1o la carga en barcazas se encuentra suspendida por el bajo nivel del r\u00edo. El calado no resiste la navegaci\u00f3n, a\u00fan con los esfuerzos realizados por el dragado.<\/p>\n<p>Cabe recordar que el n\u00famero de registro actual del r\u00edo cercano al 1,20 metros se da tras dos meses en que la marca no superaba el metro. Sin embargo, todo indica que el nivel volver\u00e1 a descender a niveles cr\u00edticos si las precipitaciones no ayudan.<\/p>\n<p>\u2018Si aumenta el nivel el riacho, al menos a 1,70 metros creo que podr\u00e1 empezar la actividad, al menos de las areneras que hoy no pueden trabajar porque no da el calado para que ingresen.<\/p>\n<p>Si aumenta un poco m\u00e1s luego, podr\u00e1 incorporarse la operaci\u00f3n de barcazas de combustible, y otras actividades que se agregar\u00e1n de forma paulatina\u201d, indic\u00f3 Ben\u00edtez.<\/p>\n<p>En este marco, agreg\u00f3 que hoy la actividad portuaria se reduce a log\u00edstica terrestre, en camiones y ferrocarril.<\/p>\n<p>\u201cSeg\u00fan la informaci\u00f3n que manejamos en octubre habr\u00eda mejores m\u00e1rgenes, pero la naturaleza no siempre es predecible\u201d, expres\u00f3.<\/p>\n<p>De esta manera, hay un amplio sector productivo que espera que ocurran precipitaciones en las altas cuencas del r\u00edo Paran\u00e1.<\/p>\n<p>DIARIO NORTE.-<\/p>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La log\u00edstica en el puerto de Barranqueras, por camiones y trenes. Se profundiza una crisis que lleva m\u00e1s de un a\u00f1o. El pron\u00f3stico no es alentador. El r\u00edo Paran\u00e1 con el hidr\u00f3metro en Barranqueras contin\u00faa registrando n\u00fameros poco alentadores, en una bajante hist\u00f3rica, sostenida en el tiempo por hace m\u00e1s de un a\u00f1o.Y el horizonte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[60],"class_list":["post-11781","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-featured"],"_links":{"self":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11781"}],"version-history":[{"count":0,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11782"}],"wp:attachment":[{"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chacosintesis.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}